{"id":634817,"date":"2026-03-28T19:38:18","date_gmt":"2026-03-28T22:38:18","guid":{"rendered":"https:\/\/hillsong.com\/argentina\/?p=634817"},"modified":"2026-03-28T19:50:31","modified_gmt":"2026-03-28T22:50:31","slug":"dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion","status":"publish","type":"post","link":"https:\/\/hillsong.com\/argentina\/ja\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/","title":{"rendered":"D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ja\">\u7533\u3057\u8a33\u3042\u308a\u307e\u305b\u3093\u3001\u3053\u306e\u30b3\u30f3\u30c6\u30f3\u30c4\u306f\u305f\u3060\u4eca\u3000<a href=\"https:\/\/hillsong.com\/argentina\/en\/wp-json\/wp\/v2\/posts\/634817\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>\u3000\u306e\u307f\u3067\u3059\u3002<\/p><p><\/p>\n<p class=\"p1\">\u201cEl \u00e1ngel dijo a las mujeres: \u2014No tengan miedo; s\u00e9 que ustedes buscan a Jes\u00fas, el que fue crucificado. No est\u00e1 aqu\u00ed, pues ha resucitado, tal como dijo. Vengan a ver el lugar donde estaba. Luego vayan pronto a decirles a sus disc\u00edpulos: \u201c\u00c9l se ha levantado de entre los muertos y va delante de ustedes a Galilea. All\u00ed lo ver\u00e1n\u201d. Eso vine a decirles. As\u00ed que las asustadas mujeres se alejaron a toda prisa del sepulcro, pero muy alegres corrieron a dar la noticia a los disc\u00edpulos. En eso Jes\u00fas les sali\u00f3 al encuentro y las salud\u00f3. Ellas se acercaron, abrazaron sus pies y lo adoraron. \u2014No tengan miedo \u2014dijo Jes\u00fas\u2014. Vayan a decirles a mis hermanos que se dirijan a Galilea y all\u00ed me ver\u00e1n\u201d.<\/p>\n<p class=\"p1\">La resurrecci\u00f3n es un acontecimiento verdaderamente c\u00f3smico: un terremoto, la aparici\u00f3n de un \u00e1ngel y una tumba vac\u00eda. Luego de este encuentro, el \u00e1ngel orden\u00f3 a las mujeres que no tuvieran miedo y las envi\u00f3 a difundir la noticia y a ver a Jes\u00fas resucitado.<\/p>\n<p class=\"p1\">La resurrecci\u00f3n tambi\u00e9n demuestra el triunfo del plan divino sobre el humano. Como aprendemos en el Evangelio de Mateo, las autoridades humanas, que se encargaron de la crucifixi\u00f3n de Jes\u00fas, estaban tan preocupadas de que Su legado perdurara bajo una \u201cresurrecci\u00f3n falsa\u201d que hicieron todo lo posible para terminar con el ministerio de Jes\u00fas de una vez por todas. No solo cubrieron la tumba con una piedra inamovible, sino que la aseguraron con un sello y la protegieron con un guardia en la entrada. Sin embargo, \u00a1la piedra se movi\u00f3, el sello se parti\u00f3 y el guardia qued\u00f3 aterrorizado!<\/p>\n<p class=\"p1\">Quiz\u00e1s como un ingenioso recordatorio de la supremac\u00eda del plan de Dios, Su mensajero, el \u00e1ngel, se sent\u00f3 sobre la piedra: \u00a1las obras del enemigo est\u00e1n verdaderamente bajo los pies divinos! (V\u00e9ase Salmo 110:1)<\/p>\n<p class=\"p1\">Leemos que las mujeres tambi\u00e9n ten\u00edan miedo, pero estaban \u201cmuy alegres\u201d (Mateo 28:8 NVI). A\u00fan no hab\u00edan visto a Jes\u00fas en persona, pero cre\u00edan que el mensaje del \u00e1ngel era cierto. Hab\u00eda una tensi\u00f3n aqu\u00ed: no ten\u00edan todas las respuestas, pero ten\u00edan esperanza; estaban desconcertadas en el presente, pero confiadas en el futuro.<\/p>\n<p class=\"p1\">Esta tensi\u00f3n es la misma que sentimos nosotros hoy: vivimos a la luz de SU resurrecci\u00f3n en el presente y creemos en NUESTRA resurrecci\u00f3n en el futuro. La victoria es real, pero tambi\u00e9n se est\u00e1 desarrollando, ahora Y no todav\u00eda. La Pascua no es solo el cap\u00edtulo final victorioso de la historia de Jes\u00fas, sino el cap\u00edtulo inicial lleno de esperanza de nuestra propia historia de fe.<\/p>\n<p class=\"p1\">La esperanza de la Pascua no se basa en tener todas las respuestas o en obtener inmediatamente todo lo que queremos, sino en poner nuestra confianza en la victoria de Jes\u00fas y experimentar un adelanto de esa victoria en nuestras vidas hoy.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>Preguntas de reflexi\u00f3n:<\/strong> <\/span><\/p>\n<p class=\"p1\">\u2022 Tanto el \u00e1ngel como Jes\u00fas ordenaron a las mujeres que no tuvieran miedo. \u00bfHay alg\u00fan aspecto de mi vida en el que necesito dejar a un lado el miedo y armarme de valor?<\/p>\n<p class=\"p1\">\u2022 El \u00e1ngel les dice a las mujeres que Jes\u00fas se hab\u00eda adelantado hacia Galilea. \u00bfQu\u00e9 oportunidades, desaf\u00edos y\/o logros tengo por delante?<\/p>\n<p class=\"p1\">\u2022 Tanto el \u00e1ngel como Jes\u00fas les piden a las mujeres que compartan la buena noticia con los disc\u00edpulos. \u00bfQu\u00e9 buena noticia puedes compartir que sea una bendici\u00f3n para otras personas?<\/p>\n<p class=\"p1\"><strong><span class=\"s1\">Idea para poner en pr\u00e1ctica:<\/span><\/strong><\/p>\n<p class=\"p1\">1. Escribe el nombre de alguien en tu vida que necesite escuchar la buena noticia de la Pascua y de alguien que conozca la buena noticia de la Pascua, pero necesite esperanza y \u00e1nimo.<\/p>\n<p class=\"p1\">2. Ora por ellos y n\u00f3mbralos en tus oraciones.<\/p>\n<p class=\"p1\">3. Habla con ellos intencionalmente esta semana y comparte la buena noticia de la Pascua.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>Escrituras:<\/strong> <\/span><\/p>\n<p class=\"p1\"><em>Mateo 28:5-10 (NVI)<\/em><br \/>\n<em>\u201cEl \u00e1ngel dijo a las mujeres: \u2014No tengan miedo; s\u00e9 que ustedes buscan a Jes\u00fas, el que fue crucificado. No est\u00e1 aqu\u00ed, pues ha resucitado, tal como dijo. Vengan a ver el lugar donde estaba. Luego vayan pronto a decirles a sus disc\u00edpulos: \u201c\u00c9l se ha levantado de entre los muertos y va delante de ustedes a Galilea. All\u00ed lo ver\u00e1n\u201d. Eso vine a decirles. As\u00ed que las asustadas mujeres se alejaron a toda prisa del sepulcro, pero muy alegres corrieron a dar la noticia a los disc\u00edpulos. En eso Jes\u00fas les sali\u00f3 al encuentro y las salud\u00f3. Ellas se acercaron, abrazaron sus pies y lo adoraron. \u2014No tengan miedo \u2014dijo Jes\u00fas\u2014. Vayan a decirles a mis hermanos que se dirijan a Galilea y all\u00ed me ver\u00e1n\u201d.<\/em><\/p>\n<p class=\"p1\"><em>Salmo 110:1 (NVI)<\/em><br \/>\n<em>\u201cAs\u00ed dijo el Se\u00f1or a mi Se\u00f1or: \u00abSi\u00e9ntate a mi derecha, hasta que ponga a tus enemigos por debajo de tus pies\u00bb&#8221;.<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u7533\u3057\u8a33\u3042\u308a\u307e\u305b\u3093\u3001\u3053\u306e\u30b3\u30f3\u30c6\u30f3\u30c4\u306f\u305f\u3060\u4eca\u3000English\u3000\u306e\u307f\u3067\u3059\u3002 \u201cEl \u00e1ngel dijo a las mujeres: \u2014No tengan miedo; s\u00e9 que ustedes buscan a Jes\u00fas, el que fue crucificado. No est\u00e1 aqu\u00ed, pues ha resucitado, tal como dijo. Vengan a ver el lugar donde estaba. Luego vayan pronto a decirles a sus disc\u00edpulos: \u201c\u00c9l se ha levantado de entre los muertos y va delante [&hellip;]<\/p>\n","protected":false},"author":54261,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-634817","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n[:] - Argentina\" \/>\n<meta property=\"og:description\" content=\"\u7533\u3057\u8a33\u3042\u308a\u307e\u305b\u3093\u3001\u3053\u306e\u30b3\u30f3\u30c6\u30f3\u30c4\u306f\u305f\u3060\u4eca\u3000English\u3000\u306e\u307f\u3067\u3059\u3002 \u201cEl \u00e1ngel dijo a las mujeres: \u2014No tengan miedo; s\u00e9 que ustedes buscan a Jes\u00fas, el que fue crucificado. No est\u00e1 aqu\u00ed, pues ha resucitado, tal como dijo. Vengan a ver el lugar donde estaba. Luego vayan pronto a decirles a sus disc\u00edpulos: \u201c\u00c9l se ha levantado de entre los muertos y va delante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Argentina\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-28T22:38:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T22:50:31+00:00\" \/>\n<meta name=\"author\" content=\"emanuellopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emanuellopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\"},\"author\":{\"name\":\"emanuellopez\",\"@id\":\"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0\"},\"headline\":\"D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n\",\"datePublished\":\"2026-03-28T22:38:18+00:00\",\"dateModified\":\"2026-03-28T22:50:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\"},\"wordCount\":847,\"commentCount\":0,\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\",\"url\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\",\"name\":\"[:en]D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n[:] - Argentina\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/argentina\/es\/#website\"},\"datePublished\":\"2026-03-28T22:38:18+00:00\",\"dateModified\":\"2026-03-28T22:50:31+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/argentina\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/argentina\/es\/#website\",\"url\":\"https:\/\/hillsong.com\/argentina\/es\/\",\"name\":\"Argentina\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/argentina\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0\",\"name\":\"emanuellopez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g\",\"caption\":\"emanuellopez\"},\"url\":\"https:\/\/hillsong.com\/argentina\/ja\/author\/emanuellopez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n[:] - Argentina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/","og_locale":"ja_JP","og_type":"article","og_title":"[:en]D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n[:] - Argentina","og_description":"\u7533\u3057\u8a33\u3042\u308a\u307e\u305b\u3093\u3001\u3053\u306e\u30b3\u30f3\u30c6\u30f3\u30c4\u306f\u305f\u3060\u4eca\u3000English\u3000\u306e\u307f\u3067\u3059\u3002 \u201cEl \u00e1ngel dijo a las mujeres: \u2014No tengan miedo; s\u00e9 que ustedes buscan a Jes\u00fas, el que fue crucificado. No est\u00e1 aqu\u00ed, pues ha resucitado, tal como dijo. Vengan a ver el lugar donde estaba. Luego vayan pronto a decirles a sus disc\u00edpulos: \u201c\u00c9l se ha levantado de entre los muertos y va delante [&hellip;]","og_url":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/","og_site_name":"Argentina","article_published_time":"2026-03-28T22:38:18+00:00","article_modified_time":"2026-03-28T22:50:31+00:00","author":"emanuellopez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emanuellopez","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/"},"author":{"name":"emanuellopez","@id":"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0"},"headline":"D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n","datePublished":"2026-03-28T22:38:18+00:00","dateModified":"2026-03-28T22:50:31+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/"},"wordCount":847,"commentCount":0,"inLanguage":"ja","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/","url":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/","name":"[:en]D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n[:] - Argentina","isPartOf":{"@id":"https:\/\/hillsong.com\/argentina\/es\/#website"},"datePublished":"2026-03-28T22:38:18+00:00","dateModified":"2026-03-28T22:50:31+00:00","author":{"@id":"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/argentina\/blog\/2026\/03\/dia-6-domingo-de-pascua-la-victoria-de-la-resurreccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/argentina\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda 6 \u2013 Domingo de pascua: La victoria de la resurrecci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/argentina\/es\/#website","url":"https:\/\/hillsong.com\/argentina\/es\/","name":"Argentina","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/argentina\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/hillsong.com\/argentina\/es\/#\/schema\/person\/211de78e89b22a6e7aaedf06154dddf0","name":"emanuellopez","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26bb781f0ad5aa160b2a49490b5bc065142c0a7e41b1d11a6f7d99f3490ea2d5?s=96&d=mm&r=g","caption":"emanuellopez"},"url":"https:\/\/hillsong.com\/argentina\/ja\/author\/emanuellopez\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/posts\/634817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/users\/54261"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/comments?post=634817"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/posts\/634817\/revisions"}],"predecessor-version":[{"id":634834,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/posts\/634817\/revisions\/634834"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/media?parent=634817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/categories?post=634817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/argentina\/ja\/wp-json\/wp\/v2\/tags?post=634817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}