{"id":634874,"date":"2021-11-17T01:34:09","date_gmt":"2021-11-17T04:34:09","guid":{"rendered":"https:\/\/hillsong.com\/brazil\/?p=634874"},"modified":"2021-11-17T01:34:09","modified_gmt":"2021-11-17T04:34:09","slug":"dia-10-coracoes-restaurados","status":"publish","type":"post","link":"https:\/\/hillsong.com\/brazil\/ca\/blog\/2021\/11\/dia-10-coracoes-restaurados\/","title":{"rendered":"Dia 10 &#8211; Cora\u00e7\u00f5es restaurados"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> i <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p><p><em>\u201cAfaste da sua boca as palavras perversas; fique longe dos seus l\u00e1bios a maldade.\u201d.<\/em><br \/>\n<strong>Prov\u00e9rbios 4:24 (NVI)<\/strong><\/p>\n<p><em>\u201cO Deus de toda a gra\u00e7a, que os chamou para a sua gl\u00f3ria eterna em Cristo Jesus, depois de terem sofrido durante pouco de tempo, os restaurar\u00e1, os confirmar\u00e1, lhes dar\u00e1 for\u00e7as e os por\u00e1 sobre firmes alicerces.\u201d<\/em><br \/>\n<strong>1 Pedro 5:10\u00a0(NVI)<\/strong><\/p>\n<p><em>\u201cEnt\u00e3o ensinarei os teus caminhos aos transgressores, para que os pecadores se voltem para ti.\u201d<\/em><br \/>\n<strong>Salmos 51:13 (NVI)<\/strong><\/p>\n<p><em>\u201cMeus irm\u00e3os, eu mesmo estou convencido de que voc\u00eas est\u00e3o cheios de bondade e plenamente instru\u00eddos, sendo capazes de aconselhar-se uns aos outros.\u201d<\/em><br \/>\n<strong>Romanos 15:14 (NVI)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Como est\u00e1 o seu cora\u00e7\u00e3o? O nosso cora\u00e7\u00e3o \u00e9 uma parte fundamental para que o nosso corpo continue vivo. Nele est\u00e3o os nossos sentimentos e emo\u00e7\u00f5es, e \u00e9 muito importante analisarmos onde temos colocado o nosso cora\u00e7\u00e3o. A Palavra de Deus diz em Prov\u00e9rbios 4:23 (NVI): \u201cAcima de tudo, guarde o seu cora\u00e7\u00e3o, pois dele depende toda a sua vida.\u201d Muitas vezes, colocamos o nosso cora\u00e7\u00e3o em pessoas, em coisas materiais, em dinheiro, em carreira, em projetos. Quantas s\u00e3o as pessoas que investimos e amamos e que nos decepcionam?<\/p>\n<p>\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido. Se ele estiver guardado em um lugar seguro, mesmo que soframos decep\u00e7\u00f5es e tristezas, nada poder\u00e1 corromp\u00ea-lo.<\/p>\n<p>Entregamos nosso cora\u00e7\u00e3o a Cristo quando conhecemos Sua gra\u00e7a e Seu amor. Assim, entendemos que precisamos que Ele tome conta de todas as nossas paix\u00f5es, para que sejam controladas pelo Esp\u00edrito Santo, e n\u00e3o por nossos pr\u00f3prios sentimentos. Essa deve ser uma decis\u00e3o di\u00e1ria.<\/p>\n<p>Quantas vezes nos frustramos e nos entristecemos com as coisas da vida? Quando guardamos o nosso cora\u00e7\u00e3o no Senhor, mesmo que as circunst\u00e2ncias nos desapontem, nosso cora\u00e7\u00e3o n\u00e3o vai se perder, pois ele est\u00e1 firmado no melhor lugar, onde podemos receber cura e restaura\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><b>? Ora\u00e7\u00e3o:<\/b><br \/>\nSenhor, pe\u00e7o que o Senhor tome conta de todo o meu cora\u00e7\u00e3o. N\u00e3o me deixe me perder em meus pr\u00f3prios sentimentos, mas me ensina a amar e perdoar como o Senhor fez por mim. Obrigado porque o Senhor me restaurou e, hoje, posso viver em paz e esperan\u00e7a. Em nome de Jesus. Am\u00e9m.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" id=\"devo\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/abgG-U-lsuY\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> i <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/634874\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p>\n<p>\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.<\/p>\n","protected":false},"author":54117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15474,15055,15053],"tags":[],"class_list":["post-634874","post","type-post","status-publish","format-standard","hentry","category-coracao-pela-casa-2021","category-devocional-blog","category-sao-paulo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Dia 10 - Cora\u00e7\u00f5es restaurados [:pt]Dia 10 - Cora\u00e7\u00f5es restaurados [:pb]Dia 10 - Cora\u00e7\u00f5es restaurados[:] | Brazil\" \/>\n<meta property=\"og:description\" content=\"[:en]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:pt]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:pb]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T04:34:09+00:00\" \/>\n<meta name=\"author\" content=\"Arthur Zarpelon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Zarpelon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\"},\"author\":{\"name\":\"Arthur Zarpelon\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\"},\"headline\":\"Dia 10 &#8211; Cora\u00e7\u00f5es restaurados\",\"datePublished\":\"2021-11-17T04:34:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\"},\"wordCount\":1215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"articleSection\":[\"Cora\u00e7\u00e3o Pela Casa 2021\",\"Devocional\",\"Sao Paulo\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\",\"url\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\",\"name\":\"[:en]Dia 10 - Cora\u00e7\u00f5es restaurados [:pt]Dia 10 - Cora\u00e7\u00f5es restaurados [:pb]Dia 10 - Cora\u00e7\u00f5es restaurados[:] | Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\"},\"datePublished\":\"2021-11-17T04:34:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/brazil\/no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia 10 &#8211; Cora\u00e7\u00f5es restaurados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"name\":\"Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\",\"name\":\"Hillsong Church Brasil\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"contentUrl\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"width\":600,\"height\":600,\"caption\":\"Hillsong Church Brasil\"},\"image\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\",\"name\":\"Arthur Zarpelon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"caption\":\"Arthur Zarpelon\"},\"url\":\"https:\/\/hillsong.com\/brazil\/ca\/author\/arthurzarpelon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Dia 10 - Cora\u00e7\u00f5es restaurados [:pt]Dia 10 - Cora\u00e7\u00f5es restaurados [:pb]Dia 10 - Cora\u00e7\u00f5es restaurados[:] | Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/","og_locale":"ca_ES","og_type":"article","og_title":"[:en]Dia 10 - Cora\u00e7\u00f5es restaurados [:pt]Dia 10 - Cora\u00e7\u00f5es restaurados [:pb]Dia 10 - Cora\u00e7\u00f5es restaurados[:] | Brazil","og_description":"[:en]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:pt]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:pb]\u00c9 muito importante cuidarmos para que o nosso cora\u00e7\u00e3o esteja protegido.[:]","og_url":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/","og_site_name":"Brazil","article_published_time":"2021-11-17T04:34:09+00:00","author":"Arthur Zarpelon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arthur Zarpelon","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/"},"author":{"name":"Arthur Zarpelon","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539"},"headline":"Dia 10 &#8211; Cora\u00e7\u00f5es restaurados","datePublished":"2021-11-17T04:34:09+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/"},"wordCount":1215,"commentCount":0,"publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"articleSection":["Cora\u00e7\u00e3o Pela Casa 2021","Devocional","Sao Paulo"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/","url":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/","name":"[:en]Dia 10 - Cora\u00e7\u00f5es restaurados [:pt]Dia 10 - Cora\u00e7\u00f5es restaurados [:pb]Dia 10 - Cora\u00e7\u00f5es restaurados[:] | Brazil","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#website"},"datePublished":"2021-11-17T04:34:09+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-10-coracoes-restaurados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/brazil\/no\/"},{"@type":"ListItem","position":2,"name":"Dia 10 &#8211; Cora\u00e7\u00f5es restaurados"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/brazil\/no\/#website","url":"https:\/\/hillsong.com\/brazil\/no\/","name":"Brazil","description":"","publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/hillsong.com\/brazil\/no\/#organization","name":"Hillsong Church Brasil","url":"https:\/\/hillsong.com\/brazil\/no\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","contentUrl":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","width":600,"height":600,"caption":"Hillsong Church Brasil"},"image":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539","name":"Arthur Zarpelon","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","caption":"Arthur Zarpelon"},"url":"https:\/\/hillsong.com\/brazil\/ca\/author\/arthurzarpelon\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/634874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/users\/54117"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/comments?post=634874"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/634874\/revisions"}],"predecessor-version":[{"id":634885,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/634874\/revisions\/634885"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/media?parent=634874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/categories?post=634874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/tags?post=634874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}