{"id":639991,"date":"2025-05-18T17:13:45","date_gmt":"2025-05-18T20:13:45","guid":{"rendered":"https:\/\/hillsong.com\/brazil\/?p=639991"},"modified":"2025-07-14T12:23:22","modified_gmt":"2025-07-14T15:23:22","slug":"quando-nao-sabemos-o-que-fazer","status":"publish","type":"post","link":"https:\/\/hillsong.com\/brazil\/ca\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/","title":{"rendered":"Quando N\u00e3o Sabemos o que Fazer"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/639991\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> i <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/639991\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p><p><\/p>\n<p class=\"e-9652-text encore-text-title-large encore-internal-color-text-base\" data-encore-id=\"text\"><em>Nos momentos da vida em que n\u00e3o sabemos o que fazer, devemos recorrer a Deus, seguir suas instru\u00e7\u00f5es e adorar o Seu nome. Pois a batalha \u00e9 do Senhor e Ele sempre estar\u00e1 conosco.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Ou\u00e7a a mensagem completa clicando no player abaixo:<\/p>\n<p><iframe style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6O66svFzX1bdlqOVIi8I9j?utm_source=generator\" width=\"100%\" height=\"352\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/639991\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> i <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/639991\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p>\n<p>Mensagem do dia 18 de maio de 2025 do campus Zona Sul.<\/p>\n","protected":false},"author":54255,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15081,15053,15486],"tags":[],"class_list":["post-639991","post","type-post","status-publish","format-standard","hentry","category-podcasts-sao-paulo","category-sao-paulo","category-zona-sul"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Quando N\u00e3o Sabemos o que Fazer[:pb]Quando N\u00e3o Sabemos o que Fazer[:] | Brazil\" \/>\n<meta property=\"og:description\" content=\"[:en]Mensagem do dia 18 de maio de 2025 do campus Zona Sul.[:pb]Mensagem do dia 18 de maio de 2025 do campus Zona Sul.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T20:13:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T15:23:22+00:00\" \/>\n<meta name=\"author\" content=\"vitorandrebrito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"vitorandrebrito\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\"},\"author\":{\"name\":\"vitorandrebrito\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/97af2450b013183b2a1f167dd4524444\"},\"headline\":\"Quando N\u00e3o Sabemos o que Fazer\",\"datePublished\":\"2025-05-18T20:13:45+00:00\",\"dateModified\":\"2025-07-14T15:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"articleSection\":[\"Podcasts\",\"Sao Paulo\",\"Zona Sul\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\",\"url\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\",\"name\":\"[:en]Quando N\u00e3o Sabemos o que Fazer[:pb]Quando N\u00e3o Sabemos o que Fazer[:] | Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\"},\"datePublished\":\"2025-05-18T20:13:45+00:00\",\"dateModified\":\"2025-07-14T15:23:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/brazil\/no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando N\u00e3o Sabemos o que Fazer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"name\":\"Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\",\"name\":\"Hillsong Church Brasil\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"contentUrl\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"width\":600,\"height\":600,\"caption\":\"Hillsong Church Brasil\"},\"image\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/97af2450b013183b2a1f167dd4524444\",\"name\":\"vitorandrebrito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g\",\"caption\":\"vitorandrebrito\"},\"url\":\"https:\/\/hillsong.com\/brazil\/ca\/author\/vitorandrebrito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Quando N\u00e3o Sabemos o que Fazer[:pb]Quando N\u00e3o Sabemos o que Fazer[:] | Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/","og_locale":"ca_ES","og_type":"article","og_title":"[:en]Quando N\u00e3o Sabemos o que Fazer[:pb]Quando N\u00e3o Sabemos o que Fazer[:] | Brazil","og_description":"[:en]Mensagem do dia 18 de maio de 2025 do campus Zona Sul.[:pb]Mensagem do dia 18 de maio de 2025 do campus Zona Sul.[:]","og_url":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/","og_site_name":"Brazil","article_published_time":"2025-05-18T20:13:45+00:00","article_modified_time":"2025-07-14T15:23:22+00:00","author":"vitorandrebrito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"vitorandrebrito"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/"},"author":{"name":"vitorandrebrito","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/97af2450b013183b2a1f167dd4524444"},"headline":"Quando N\u00e3o Sabemos o que Fazer","datePublished":"2025-05-18T20:13:45+00:00","dateModified":"2025-07-14T15:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"articleSection":["Podcasts","Sao Paulo","Zona Sul"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/","url":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/","name":"[:en]Quando N\u00e3o Sabemos o que Fazer[:pb]Quando N\u00e3o Sabemos o que Fazer[:] | Brazil","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#website"},"datePublished":"2025-05-18T20:13:45+00:00","dateModified":"2025-07-14T15:23:22+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/brazil\/podcast\/2025\/05\/quando-nao-sabemos-o-que-fazer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/brazil\/no\/"},{"@type":"ListItem","position":2,"name":"Quando N\u00e3o Sabemos o que Fazer"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/brazil\/no\/#website","url":"https:\/\/hillsong.com\/brazil\/no\/","name":"Brazil","description":"","publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/hillsong.com\/brazil\/no\/#organization","name":"Hillsong Church Brasil","url":"https:\/\/hillsong.com\/brazil\/no\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","contentUrl":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","width":600,"height":600,"caption":"Hillsong Church Brasil"},"image":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/97af2450b013183b2a1f167dd4524444","name":"vitorandrebrito","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/744922f6432d8661886f91b44c7bf0a3e6b50441613bff9c5840e7e8b8a4b422?s=96&d=mm&r=g","caption":"vitorandrebrito"},"url":"https:\/\/hillsong.com\/brazil\/ca\/author\/vitorandrebrito\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/639991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/users\/54255"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/comments?post=639991"}],"version-history":[{"count":4,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/639991\/revisions"}],"predecessor-version":[{"id":640174,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/posts\/639991\/revisions\/640174"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/media?parent=639991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/categories?post=639991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/ca\/wp-json\/wp\/v2\/tags?post=639991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}