{"id":634899,"date":"2021-11-21T00:00:06","date_gmt":"2021-11-21T03:00:06","guid":{"rendered":"https:\/\/hillsong.com\/brazil\/?p=634899"},"modified":"2021-11-21T00:09:21","modified_gmt":"2021-11-21T03:09:21","slug":"dia-14-restaurados-para-sua-causa","status":"publish","type":"post","link":"https:\/\/hillsong.com\/brazil\/fr\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/","title":{"rendered":"Dia 14 &#8211; Restaurados para Sua causa"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> et <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p><p><em>Esse mist\u00e9rio permaneceu sem ser esclarecido por muito tempo, mas agora \u00e9 desvendado. Deus quis que todos, n\u00e3o apenas os judeus, conhecessem esse rico e glorioso segredo por dentro e por fora, independentemente de origem e de filia\u00e7\u00e3o religiosa. O mist\u00e9rio, em poucas palavras, \u00e9 este: Cristo est\u00e1 em voc\u00eas, e isso d\u00e1 a voc\u00eas a esperan\u00e7a de participar da gl\u00f3ria de Deus. Simples assim.<\/em><br \/>\n<strong>Colossenses 1:26-27 (A Mensagem)<\/strong><\/p>\n<p>Toda a Escritura fala sobre a busca de sentido e prop\u00f3sito. Apesar de estar preso, o ap\u00f3stolo Paulo deixou que esse confinamento cultivasse a Verdade em seu cora\u00e7\u00e3o para transform\u00e1-la em uma revela\u00e7\u00e3o profunda, que se converteu na voz do Esp\u00edrito de Deus para n\u00f3s atrav\u00e9s das suas cartas. Paulo entendeu que era o conhecimento da Verdade que nos liberta, e n\u00e3o uma s\u00e9rie de circunst\u00e2ncias.<\/p>\n<p>O mist\u00e9rio \u00e9 o pr\u00f3prio Cristo em voc\u00ea. Colossenses 2:3 (A Mensagem) diz: &#8220;Todos os ricos tesouros da sabedoria e do conhecimento est\u00e3o incrustados nesse mist\u00e9rio.&#8221; J\u00e1 que Ele habita em voc\u00ea, separe um tempo para estar em Sua presen\u00e7a, abrace a verdade da Sua Palavra e permita que tudo o que Ele \u00e9 transforme voc\u00ea \u00e0 Sua imagem e semelhan\u00e7a. &#8220;N\u00e3o h\u00e1 outra Mensagem \u2014 apenas esta. Toda criatura debaixo do c\u00e9u ouve a mesma Mensagem. Eu, Paulo, sou mensageiro desta Mensagem.&#8221; (Colossenses 1:23 &#8211; A Mensagem).<\/p>\n<p>Na nossa igreja, cantamos uma m\u00fasica <em>Outro na Fornalha<\/em> (Hillsong United). Sempre que cantamos essa m\u00fasica, lembro-me de que, \u00e0s vezes, precisamos passar por algum tipo de &#8220;fornalha&#8221; em nossa vida para realmente entender o poder da Sua mensagem. Se voc\u00ea estiver passando por uma &#8220;fornalha&#8221; neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea, e que Sua fidelidade e bondade significam que Ele est\u00e1 totalmente comprometido com voc\u00ea, aconte\u00e7a o que acontecer.<\/p>\n<p>Colossenses 1:15, na vers\u00e3o a Mensagem, diz: &#8220;Quando olhamos para o Filho, vemos o Deus invis\u00edvel.&#8221; Minha ora\u00e7\u00e3o \u00e9 que o Cristo que est\u00e1 em voc\u00ea, que nunca muda e personifica a miseric\u00f3rdia, a gentileza e a gra\u00e7a de Deus, que tornou o Deus invis\u00edvel vis\u00edvel, seja visto por meio de voc\u00ea.<\/p>\n<p>&nbsp;<\/p>\n<p><b>? Ora\u00e7\u00e3o:<\/b><br \/>\nObrigado, Jesus, porque restauras minha vida com um prop\u00f3sito. Pe\u00e7o que as chamas que eu possa atravessar sirvam para purificar meu cora\u00e7\u00e3o e transformar meu car\u00e1ter. Obrigado por caminhar comigo em todo momento. Am\u00e9m.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/hp3GWfaSNxA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> et <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/634899\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p>\n<p>Se voc\u00ea estiver passando por uma &#8220;fornalha&#8221; neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea<\/p>\n","protected":false},"author":54117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15474,15055,15053],"tags":[],"class_list":["post-634899","post","type-post","status-publish","format-standard","hentry","category-coracao-pela-casa-2021","category-devocional-blog","category-sao-paulo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Dia 14 - Restaurados para Sua causa[:pt]Dia 14 - Restaurados para Sua causa[:pb]Dia 14 - Restaurados para Sua causa[:] | Brazil\" \/>\n<meta property=\"og:description\" content=\"[:en]Se voc\u00ea estiver passando por uma &quot;fornalha&quot; neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:pt]Se voc\u00ea estiver passando por uma &quot;fornalha&quot; neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:pb]Se voc\u00ea estiver passando por uma &quot;fornalha&quot; neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-21T03:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-21T03:09:21+00:00\" \/>\n<meta name=\"author\" content=\"Arthur Zarpelon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Zarpelon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\"},\"author\":{\"name\":\"Arthur Zarpelon\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\"},\"headline\":\"Dia 14 &#8211; Restaurados para Sua causa\",\"datePublished\":\"2021-11-21T03:00:06+00:00\",\"dateModified\":\"2021-11-21T03:09:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\"},\"wordCount\":1278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"articleSection\":[\"Cora\u00e7\u00e3o Pela Casa 2021\",\"Devocional\",\"Sao Paulo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\",\"url\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\",\"name\":\"[:en]Dia 14 - Restaurados para Sua causa[:pt]Dia 14 - Restaurados para Sua causa[:pb]Dia 14 - Restaurados para Sua causa[:] | Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\"},\"datePublished\":\"2021-11-21T03:00:06+00:00\",\"dateModified\":\"2021-11-21T03:09:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/brazil\/no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia 14 &#8211; Restaurados para Sua causa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"name\":\"Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\",\"name\":\"Hillsong Church Brasil\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"contentUrl\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"width\":600,\"height\":600,\"caption\":\"Hillsong Church Brasil\"},\"image\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\",\"name\":\"Arthur Zarpelon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"caption\":\"Arthur Zarpelon\"},\"url\":\"https:\/\/hillsong.com\/brazil\/fr\/author\/arthurzarpelon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Dia 14 - Restaurados para Sua causa[:pt]Dia 14 - Restaurados para Sua causa[:pb]Dia 14 - Restaurados para Sua causa[:] | Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/","og_locale":"fr_FR","og_type":"article","og_title":"[:en]Dia 14 - Restaurados para Sua causa[:pt]Dia 14 - Restaurados para Sua causa[:pb]Dia 14 - Restaurados para Sua causa[:] | Brazil","og_description":"[:en]Se voc\u00ea estiver passando por uma \"fornalha\" neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:pt]Se voc\u00ea estiver passando por uma \"fornalha\" neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:pb]Se voc\u00ea estiver passando por uma \"fornalha\" neste momento, lembre-se de que Cristo est\u00e1 com voc\u00ea[:]","og_url":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/","og_site_name":"Brazil","article_published_time":"2021-11-21T03:00:06+00:00","article_modified_time":"2021-11-21T03:09:21+00:00","author":"Arthur Zarpelon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arthur Zarpelon","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/"},"author":{"name":"Arthur Zarpelon","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539"},"headline":"Dia 14 &#8211; Restaurados para Sua causa","datePublished":"2021-11-21T03:00:06+00:00","dateModified":"2021-11-21T03:09:21+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/"},"wordCount":1278,"commentCount":0,"publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"articleSection":["Cora\u00e7\u00e3o Pela Casa 2021","Devocional","Sao Paulo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/","url":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/","name":"[:en]Dia 14 - Restaurados para Sua causa[:pt]Dia 14 - Restaurados para Sua causa[:pb]Dia 14 - Restaurados para Sua causa[:] | Brazil","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#website"},"datePublished":"2021-11-21T03:00:06+00:00","dateModified":"2021-11-21T03:09:21+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/brazil\/blog\/2021\/11\/dia-14-restaurados-para-sua-causa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/brazil\/no\/"},{"@type":"ListItem","position":2,"name":"Dia 14 &#8211; Restaurados para Sua causa"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/brazil\/no\/#website","url":"https:\/\/hillsong.com\/brazil\/no\/","name":"Brazil","description":"","publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hillsong.com\/brazil\/no\/#organization","name":"Hillsong Church Brasil","url":"https:\/\/hillsong.com\/brazil\/no\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","contentUrl":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","width":600,"height":600,"caption":"Hillsong Church Brasil"},"image":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539","name":"Arthur Zarpelon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","caption":"Arthur Zarpelon"},"url":"https:\/\/hillsong.com\/brazil\/fr\/author\/arthurzarpelon\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/634899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/users\/54117"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/comments?post=634899"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/634899\/revisions"}],"predecessor-version":[{"id":634940,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/634899\/revisions\/634940"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/media?parent=634899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/categories?post=634899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/tags?post=634899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}