{"id":635689,"date":"2022-05-29T17:39:58","date_gmt":"2022-05-29T20:39:58","guid":{"rendered":"https:\/\/hillsong.com\/brazil\/?p=635689"},"modified":"2022-05-29T17:39:58","modified_gmt":"2022-05-29T20:39:58","slug":"noite-de-dna-6","status":"publish","type":"post","link":"https:\/\/hillsong.com\/brazil\/fr\/event\/2022\/05\/noite-de-dna-6\/","title":{"rendered":"Noite de DNA"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/635689\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> et <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/635689\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p><p>Na pr\u00f3ximo dia 7 de junho, ter\u00e7a-feira, teremos nossa Noite de DNA! N\u00e3o fique de fora desta noite em que ouvirmos do nosso pastor l\u00edder Chris Mendez sobre o cora\u00e7\u00e3o, a cultura e a lideran\u00e7a da nossa igreja. Se a Hillsong S\u00e3o Paulo \u00e9 a sua Casa, voc\u00ea n\u00e3o pode ficar de fora!<\/p>\n<p>Nos vemos l\u00e1!<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en English et Portugu\u00eas do Brasil.Na pr\u00f3ximo dia 7 de junho, ter\u00e7a-feira, teremos nossa Noite de DNA! N\u00e3o fique de fora desta noite em que ouvirmos do nosso pastor l\u00edder Chris Mendez sobre o cora\u00e7\u00e3o, a cultura e a lideran\u00e7a da nossa igreja. Se a Hillsong S\u00e3o Paulo \u00e9 [&hellip;]<\/p>\n","protected":false},"author":54117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15450,15158,15053],"tags":[],"class_list":["post-635689","post","type-post","status-publish","format-standard","hentry","category-dna","category-eventos-sao-paulo","category-sao-paulo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Noite de DNA[:pb]Noite de DNA[:] | Brazil\" \/>\n<meta property=\"og:description\" content=\"D\u00e9sol\u00e9, cet article est seulement disponible en English et Portugu\u00eas do Brasil.Na pr\u00f3ximo dia 7 de junho, ter\u00e7a-feira, teremos nossa Noite de DNA! N\u00e3o fique de fora desta noite em que ouvirmos do nosso pastor l\u00edder Chris Mendez sobre o cora\u00e7\u00e3o, a cultura e a lideran\u00e7a da nossa igreja. Se a Hillsong S\u00e3o Paulo \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-29T20:39:58+00:00\" \/>\n<meta name=\"author\" content=\"Arthur Zarpelon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Zarpelon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\"},\"author\":{\"name\":\"Arthur Zarpelon\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\"},\"headline\":\"Noite de DNA\",\"datePublished\":\"2022-05-29T20:39:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\"},\"wordCount\":134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"articleSection\":[\"DNA\",\"\",\"Sao Paulo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\",\"url\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\",\"name\":\"[:en]Noite de DNA[:pb]Noite de DNA[:] | Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\"},\"datePublished\":\"2022-05-29T20:39:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/brazil\/no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noite de DNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"name\":\"Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\",\"name\":\"Hillsong Church Brasil\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"contentUrl\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"width\":600,\"height\":600,\"caption\":\"Hillsong Church Brasil\"},\"image\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539\",\"name\":\"Arthur Zarpelon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g\",\"caption\":\"Arthur Zarpelon\"},\"url\":\"https:\/\/hillsong.com\/brazil\/fr\/author\/arthurzarpelon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Noite de DNA[:pb]Noite de DNA[:] | Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/","og_locale":"fr_FR","og_type":"article","og_title":"[:en]Noite de DNA[:pb]Noite de DNA[:] | Brazil","og_description":"D\u00e9sol\u00e9, cet article est seulement disponible en English et Portugu\u00eas do Brasil.Na pr\u00f3ximo dia 7 de junho, ter\u00e7a-feira, teremos nossa Noite de DNA! N\u00e3o fique de fora desta noite em que ouvirmos do nosso pastor l\u00edder Chris Mendez sobre o cora\u00e7\u00e3o, a cultura e a lideran\u00e7a da nossa igreja. Se a Hillsong S\u00e3o Paulo \u00e9 [&hellip;]","og_url":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/","og_site_name":"Brazil","article_published_time":"2022-05-29T20:39:58+00:00","author":"Arthur Zarpelon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arthur Zarpelon","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/"},"author":{"name":"Arthur Zarpelon","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539"},"headline":"Noite de DNA","datePublished":"2022-05-29T20:39:58+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/"},"wordCount":134,"commentCount":0,"publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"articleSection":["DNA","","Sao Paulo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/","url":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/","name":"[:en]Noite de DNA[:pb]Noite de DNA[:] | Brazil","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#website"},"datePublished":"2022-05-29T20:39:58+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/brazil\/event\/2022\/05\/noite-de-dna-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/brazil\/no\/"},{"@type":"ListItem","position":2,"name":"Noite de DNA"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/brazil\/no\/#website","url":"https:\/\/hillsong.com\/brazil\/no\/","name":"Brazil","description":"","publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hillsong.com\/brazil\/no\/#organization","name":"Hillsong Church Brasil","url":"https:\/\/hillsong.com\/brazil\/no\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","contentUrl":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","width":600,"height":600,"caption":"Hillsong Church Brasil"},"image":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ccf8274a6836227f96f928909590a539","name":"Arthur Zarpelon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f22a2529c912912ee7bfdd81579b7d80597101cf0437bb33f9cf000ba2c6981?s=96&d=mm&r=g","caption":"Arthur Zarpelon"},"url":"https:\/\/hillsong.com\/brazil\/fr\/author\/arthurzarpelon\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/635689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/users\/54117"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/comments?post=635689"}],"version-history":[{"count":2,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/635689\/revisions"}],"predecessor-version":[{"id":635694,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/posts\/635689\/revisions\/635694"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/media?parent=635689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/categories?post=635689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/fr\/wp-json\/wp\/v2\/tags?post=635689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}