{"id":632496,"date":"2021-01-11T15:51:28","date_gmt":"2021-01-11T15:51:28","guid":{"rendered":"https:\/\/hillsong.com\/brazil\/?p=632496"},"modified":"2021-01-11T15:51:28","modified_gmt":"2021-01-11T15:51:28","slug":"dia-5-avancando-na-fe","status":"publish","type":"post","link":"https:\/\/hillsong.com\/brazil\/it\/blog\/2021\/01\/dia-5-avancando-na-fe\/","title":{"rendered":"DIA 5: Avan\u00e7ando na f\u00e9"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-it\">Ci spiace, ma questo articolo \u00e8 disponibile soltanto in <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/es\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> e <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p><p><em>&#8220;Agora n\u00e3o h\u00e1 nada entre voc\u00eas e Deus Pai, pois ele os v\u00ea como santos, sem defeitos e restaurados se, de fato, voc\u00eas continuarem avan\u00e7ando em f\u00e9 e permanecerem firmes sobre a funda\u00e7\u00e3o em que s\u00e3o edificados. Nunca sejam abalados na esperan\u00e7a do evangelho no qual voc\u00eas creem. E essa \u00e9 a gloriosa not\u00edcia que eu prego por todo o mundo.&#8221;<\/em> Colossenses 1:22-23 (TPT &#8211; Tradu\u00e7\u00e3o Livre)<\/p>\n<p>A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas. \u00c9 a nossa luz nas trevas e o amor no caos. \u00c9 nosso desafio e nosso poder transformador. As palavras de Paulo nos apontam para o c\u00e9u e nos lembram de que l\u00e1 \u00e9 nosso verdadeiro lar.<\/p>\n<p>Romanos 12:3 fala da medida de f\u00e9 que cada um de n\u00f3s recebeu. Cabe a voc\u00ea decidir o que far\u00e1 com a medida de f\u00e9 que recebeu. Voc\u00ea pode deix\u00e1-la de lado ou enterr\u00e1-la, ou pode desenvolver e cultivar sua medida de f\u00e9 para que se torne algo lindo e significante. Acredito de verdade que esses s\u00e3o os dias em que voc\u00ea precisa desenvolver a medida de f\u00e9 que lhe foi confiada.<\/p>\n<p>A verdade sobre nossas vidas \u00e9 que, \u00e0s vezes, o \u00fanico meio de crescermos \u00e9 sendo colocados em situa\u00e7\u00f5es que pressionam nossa f\u00e9. Sendo assim, cuidado para n\u00e3o desprezar esses momentos, nem lutar contra eles ou procurar algu\u00e9m ou algo para culpar. Veja-os pelo que eles s\u00e3o e permita que Deus cultive algo bom em voc\u00ea. O minist\u00e9rio de Paulo estava sob ataque e, muitas vezes, isso resultou em seu sofrimento f\u00edsico. Ainda assim, ele nunca permitiu que seu sofrimento diminu\u00edsse sua f\u00e9 ou sua mensagem. Em vez disso, ele aprofundou e aprendeu mais intensamente em seu relacionamento com Cristo e foi recompensado com uma revela\u00e7\u00e3o incr\u00edvel e uma f\u00e9 inabal\u00e1vel que permeia suas palavras, trazendo-lhe vit\u00f3ria em todas as circunst\u00e2ncias.<\/p>\n<p>Minha ora\u00e7\u00e3o \u00e9 para que a medida de f\u00e9 que voc\u00ea possui cres\u00e7a, e que uma f\u00e9 nova e viva te leve a entrar em lugares novos e surpreendentes da Sua provis\u00e3o e da Sua fidelidade.<\/p>\n<p><strong><em>Leitura: Colossenses 1:22-23; Romanos 12:1-5<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-it\">Ci spiace, ma questo articolo \u00e8 disponibile soltanto in <a href=\"https:\/\/hillsong.com\/brazil\/en\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/es\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>, <a href=\"https:\/\/hillsong.com\/brazil\/pt\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pt\" title=\"Portugu\u00eas\">Portugu\u00eas<\/a> e <a href=\"https:\/\/hillsong.com\/brazil\/pb\/wp-json\/wp\/v2\/posts\/632496\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-pb\" title=\"Portugu\u00eas do Brasil\">Portugu\u00eas do Brasil<\/a>.<\/p>\n<p>A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.<\/p>\n","protected":false},"author":15679,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15054,15055,15053],"tags":[258,14957],"class_list":["post-632496","post","type-post","status-publish","format-standard","hentry","category-blog","category-devocional-blog","category-sao-paulo","tag-bobbie-houston","tag-devocional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]DIA 5: Avan\u00e7ando na f\u00e9[:es]DIA 5: Avan\u00e7ando na f\u00e9[:pt]DIA 5: Avan\u00e7ando na f\u00e9[:pb]DIA 5: Avan\u00e7ando na f\u00e9[:] | Brazil\" \/>\n<meta property=\"og:description\" content=\"[:en]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:es]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:pt]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:pb]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\" \/>\n<meta property=\"og:site_name\" content=\"Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-11T15:51:28+00:00\" \/>\n<meta name=\"author\" content=\"Hillsong S\u00e3o Paulo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hillsong S\u00e3o Paulo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\"},\"author\":{\"name\":\"Hillsong S\u00e3o Paulo\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ff64e3a1eaa085374430ac64946b731a\"},\"headline\":\"DIA 5: Avan\u00e7ando na f\u00e9\",\"datePublished\":\"2021-01-11T15:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\"},\"wordCount\":1516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"keywords\":[\"Bobbie Houston\",\"devocional\"],\"articleSection\":[\"Blog\",\"Devocional\",\"Sao Paulo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\",\"url\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\",\"name\":\"[:en]DIA 5: Avan\u00e7ando na f\u00e9[:es]DIA 5: Avan\u00e7ando na f\u00e9[:pt]DIA 5: Avan\u00e7ando na f\u00e9[:pb]DIA 5: Avan\u00e7ando na f\u00e9[:] | Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\"},\"datePublished\":\"2021-01-11T15:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/brazil\/no\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIA 5: Avan\u00e7ando na f\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#website\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"name\":\"Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#organization\",\"name\":\"Hillsong Church Brasil\",\"url\":\"https:\/\/hillsong.com\/brazil\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"contentUrl\":\"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png\",\"width\":600,\"height\":600,\"caption\":\"Hillsong Church Brasil\"},\"image\":{\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ff64e3a1eaa085374430ac64946b731a\",\"name\":\"Hillsong S\u00e3o Paulo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g\",\"caption\":\"Hillsong S\u00e3o Paulo\"},\"sameAs\":[\"http:\/\/hillsong.com\/saopaulo\"],\"url\":\"https:\/\/hillsong.com\/brazil\/it\/author\/hillsong_saopaulo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]DIA 5: Avan\u00e7ando na f\u00e9[:es]DIA 5: Avan\u00e7ando na f\u00e9[:pt]DIA 5: Avan\u00e7ando na f\u00e9[:pb]DIA 5: Avan\u00e7ando na f\u00e9[:] | Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/","og_locale":"it_IT","og_type":"article","og_title":"[:en]DIA 5: Avan\u00e7ando na f\u00e9[:es]DIA 5: Avan\u00e7ando na f\u00e9[:pt]DIA 5: Avan\u00e7ando na f\u00e9[:pb]DIA 5: Avan\u00e7ando na f\u00e9[:] | Brazil","og_description":"[:en]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:es]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:pt]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:pb]A palavra de Deus \u00e9 tanto \u00e2ncora como b\u00fassola para nossas almas.[:]","og_url":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/","og_site_name":"Brazil","article_published_time":"2021-01-11T15:51:28+00:00","author":"Hillsong S\u00e3o Paulo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Hillsong S\u00e3o Paulo","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/"},"author":{"name":"Hillsong S\u00e3o Paulo","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ff64e3a1eaa085374430ac64946b731a"},"headline":"DIA 5: Avan\u00e7ando na f\u00e9","datePublished":"2021-01-11T15:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/"},"wordCount":1516,"commentCount":0,"publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"keywords":["Bobbie Houston","devocional"],"articleSection":["Blog","Devocional","Sao Paulo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/","url":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/","name":"[:en]DIA 5: Avan\u00e7ando na f\u00e9[:es]DIA 5: Avan\u00e7ando na f\u00e9[:pt]DIA 5: Avan\u00e7ando na f\u00e9[:pb]DIA 5: Avan\u00e7ando na f\u00e9[:] | Brazil","isPartOf":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#website"},"datePublished":"2021-01-11T15:51:28+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/brazil\/sv\/blog\/2021\/01\/dia-5-avancando-na-fe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/brazil\/no\/"},{"@type":"ListItem","position":2,"name":"DIA 5: Avan\u00e7ando na f\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/brazil\/no\/#website","url":"https:\/\/hillsong.com\/brazil\/no\/","name":"Brazil","description":"","publisher":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/brazil\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hillsong.com\/brazil\/no\/#organization","name":"Hillsong Church Brasil","url":"https:\/\/hillsong.com\/brazil\/no\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","contentUrl":"https:\/\/cdn.hillsong.com\/wp-content\/uploads\/sites\/36\/2025\/08\/31011329\/hsp-logo-bk-outline.png","width":600,"height":600,"caption":"Hillsong Church Brasil"},"image":{"@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/hillsong.com\/brazil\/no\/#\/schema\/person\/ff64e3a1eaa085374430ac64946b731a","name":"Hillsong S\u00e3o Paulo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64037c5f432b098499f48b07fadcc8e94e5ea2f1ddc091548cb55c938322df10?s=96&d=mm&r=g","caption":"Hillsong S\u00e3o Paulo"},"sameAs":["http:\/\/hillsong.com\/saopaulo"],"url":"https:\/\/hillsong.com\/brazil\/it\/author\/hillsong_saopaulo\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/posts\/632496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/users\/15679"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/comments?post=632496"}],"version-history":[{"count":1,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/posts\/632496\/revisions"}],"predecessor-version":[{"id":632497,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/posts\/632496\/revisions\/632497"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/media?parent=632496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/categories?post=632496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/brazil\/it\/wp-json\/wp\/v2\/tags?post=632496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}