{"id":506888,"date":"2018-11-21T00:00:00","date_gmt":"2018-11-21T00:00:00","guid":{"rendered":"https:\/\/hillsong.com\/?p=506888"},"modified":"2018-11-23T00:00:00","modified_gmt":"2018-11-23T00:00:00","slug":"das-wunder-der-familie","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/ca\/event\/2018\/11\/das-wunder-der-familie\/","title":{"rendered":"DAS WUNDER DER FAMILIE"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/germany\/en\/wp-json\/wp\/v2\/posts\/506888\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>.<\/p><p>Genie\u00dfe den zweiten Advent mit weihnachtlichem,<br \/>\nwarmen Essen, toller Atmosph\u00e4re in unseren Foyers und warmen Punsch, w\u00e4hrend wir im Gottesdienst von kreativen Elementen in die Botschaft von Weihnachten gef\u00fchrt werden.<\/p>\n<p>Sei bei unseren Gottesdiensten dabei.<\/p>\n<p>11 und 17 Uhr<\/p>\n<p>Wir freuen uns auf dich!<\/p>","protected":false},"excerpt":{"rendered":"<p>Ho sentim, aquesta entrada es troba disponible \u00fanicament en English.Genie\u00dfe den zweiten Advent mit weihnachtlichem, warmen Essen, toller Atmosph\u00e4re in unseren Foyers und warmen Punsch, w\u00e4hrend wir im Gottesdienst von kreativen Elementen in die Botschaft von Weihnachten gef\u00fchrt werden. Sei bei unseren Gottesdiensten dabei. 11 und 17 Uhr Wir freuen uns auf dich!<\/p>\n","protected":false},"author":1394,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[231],"tags":[285],"class_list":["post-506888","post","type-post","status-publish","format-standard","hentry","category-events-ams","tag-dusseldorf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]DAS WUNDER DER FAMILIE[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Ho sentim, aquesta entrada es troba disponible \u00fanicament en English.Genie\u00dfe den zweiten Advent mit weihnachtlichem, warmen Essen, toller Atmosph\u00e4re in unseren Foyers und warmen Punsch, w\u00e4hrend wir im Gottesdienst von kreativen Elementen in die Botschaft von Weihnachten gef\u00fchrt werden. Sei bei unseren Gottesdiensten dabei. 11 und 17 Uhr Wir freuen uns auf dich!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-21T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-23T00:00:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DAS WUNDER DER FAMILIE\",\"datePublished\":\"2018-11-21T00:00:00+00:00\",\"dateModified\":\"2018-11-23T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\"},\"wordCount\":52,\"commentCount\":0,\"keywords\":[\"Dusseldorf\"],\"articleSection\":[\"Events\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\",\"url\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\",\"name\":\"[:en]DAS WUNDER DER FAMILIE[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2018-11-21T00:00:00+00:00\",\"dateModified\":\"2018-11-23T00:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAS WUNDER DER FAMILIE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/hillsong.com\/germany\/ca\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]DAS WUNDER DER FAMILIE[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/","og_locale":"ca_ES","og_type":"article","og_title":"[:en]DAS WUNDER DER FAMILIE[:] - Dach","og_description":"Ho sentim, aquesta entrada es troba disponible \u00fanicament en English.Genie\u00dfe den zweiten Advent mit weihnachtlichem, warmen Essen, toller Atmosph\u00e4re in unseren Foyers und warmen Punsch, w\u00e4hrend wir im Gottesdienst von kreativen Elementen in die Botschaft von Weihnachten gef\u00fchrt werden. Sei bei unseren Gottesdiensten dabei. 11 und 17 Uhr Wir freuen uns auf dich!","og_url":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/","og_site_name":"Dach","article_published_time":"2018-11-21T00:00:00+00:00","article_modified_time":"2018-11-23T00:00:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/"},"author":{"name":"","@id":""},"headline":"DAS WUNDER DER FAMILIE","datePublished":"2018-11-21T00:00:00+00:00","dateModified":"2018-11-23T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/"},"wordCount":52,"commentCount":0,"keywords":["Dusseldorf"],"articleSection":["Events"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/","url":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/","name":"[:en]DAS WUNDER DER FAMILIE[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2018-11-21T00:00:00+00:00","dateModified":"2018-11-23T00:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/event\/2018\/11\/das-wunder-der-familie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"DAS WUNDER DER FAMILIE"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"","url":"https:\/\/hillsong.com\/germany\/ca\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts\/506888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/users\/1394"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/comments?post=506888"}],"version-history":[{"count":0,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts\/506888\/revisions"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/media?parent=506888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/categories?post=506888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/tags?post=506888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}