{"id":634071,"date":"2021-01-17T07:43:10","date_gmt":"2021-01-17T07:43:10","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=634071"},"modified":"2021-01-21T08:39:43","modified_gmt":"2021-01-21T08:39:43","slug":"kreuzlingen-tagerwilen-24-1","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/ca\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/","title":{"rendered":"KREUZLINGEN, T\u00c4GERWILEN | 24.1."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sentim, aquesta entrada es troba disponible \u00fanicament en <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/634071\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>WILLKOMMEN ZU MICRO CHURCH <\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil von unserem Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben. Wir treffen uns in Gruppen ab 30+ Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<br \/>\nMEDIZINISCHE MASKENPFLICHT: Ab sofort gilt in unseren Gottesdiensten die Pflicht, medizinische Masken zu tragen, dazu geh\u00f6ren OP-Masken, FFP2-Masken und Masken des Typs KN95.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ho sentim, aquesta entrada es troba disponible \u00fanicament en Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]<\/p>\n","protected":false},"author":51263,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15403,271,272],"tags":[283],"class_list":["post-634071","post","type-post","status-publish","format-standard","hentry","category-events-konstanz","category-germany","category-konstanz","tag-konstanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]KREUZLINGEN, T\u00c4GERWILEN | 24.1.[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Ho sentim, aquesta entrada es troba disponible \u00fanicament en Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-17T07:43:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-21T08:39:43+00:00\" \/>\n<meta name=\"author\" content=\"Tabea Grimm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tabea Grimm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\"},\"author\":{\"name\":\"Tabea Grimm\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"headline\":\"KREUZLINGEN, T\u00c4GERWILEN | 24.1.\",\"datePublished\":\"2021-01-17T07:43:10+00:00\",\"dateModified\":\"2021-01-21T08:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\"},\"wordCount\":118,\"commentCount\":0,\"keywords\":[\"Konstanz\"],\"articleSection\":[\"Events\",\"Germany\",\"Konstanz\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\",\"name\":\"[:de]KREUZLINGEN, T\u00c4GERWILEN | 24.1.[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2021-01-17T07:43:10+00:00\",\"dateModified\":\"2021-01-21T08:39:43+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KREUZLINGEN, T\u00c4GERWILEN | 24.1.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\",\"name\":\"Tabea Grimm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"caption\":\"Tabea Grimm\"},\"url\":\"https:\/\/hillsong.com\/germany\/ca\/author\/tabea-grimm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 24.1.[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/","og_locale":"ca_ES","og_type":"article","og_title":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 24.1.[:] - Dach","og_description":"Ho sentim, aquesta entrada es troba disponible \u00fanicament en Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/","og_site_name":"Dach","article_published_time":"2021-01-17T07:43:10+00:00","article_modified_time":"2021-01-21T08:39:43+00:00","author":"Tabea Grimm","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tabea Grimm","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/"},"author":{"name":"Tabea Grimm","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"headline":"KREUZLINGEN, T\u00c4GERWILEN | 24.1.","datePublished":"2021-01-17T07:43:10+00:00","dateModified":"2021-01-21T08:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/"},"wordCount":118,"commentCount":0,"keywords":["Konstanz"],"articleSection":["Events","Germany","Konstanz"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/","url":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/","name":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 24.1.[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2021-01-17T07:43:10+00:00","dateModified":"2021-01-21T08:39:43+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/fr\/event\/2021\/01\/kreuzlingen-tagerwilen-24-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"KREUZLINGEN, T\u00c4GERWILEN | 24.1."}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790","name":"Tabea Grimm","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","caption":"Tabea Grimm"},"url":"https:\/\/hillsong.com\/germany\/ca\/author\/tabea-grimm\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts\/634071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/users\/51263"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/comments?post=634071"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts\/634071\/revisions"}],"predecessor-version":[{"id":634201,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/posts\/634071\/revisions\/634201"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/media?parent=634071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/categories?post=634071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/ca\/wp-json\/wp\/v2\/tags?post=634071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}