{"id":420079,"date":"2017-08-15T00:00:00","date_gmt":"2017-08-15T00:00:00","guid":{"rendered":"https:\/\/hillsong.com\/?p=420079"},"modified":"2017-09-14T00:00:00","modified_gmt":"2017-09-14T00:00:00","slug":"leadership-day-mit-dooleys","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/","title":{"rendered":"Leadership Day mit Dooleys"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/hillsong.com\/germany\/en\/wp-json\/wp\/v2\/posts\/420079\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> verf\u00fcgbar.<\/p><p>es ist wirklich eine unglaubliche Freude, mit dir zusammen Kirche zu bauen!<\/p>\n<p>Wir haben uns dieses Jahr mit unserem Leiterschaftstag im Januar und durch unsere Leadership Training Nights, dem Leben &amp; Leiterschafts Blog und anderen Inputs auf die Reise gemacht, zu besseren Leitern zu werden \u2013 damit Menschen zu Jesus finden.<\/p>\n<p>F\u00fcr unseren n\u00e4chsten Schritt in unserer Leiterschaftsreise haben wir einen ganz besonderen Tag\u00a0geplant:<\/p>\n<p>Am Samstag, den 23.09. haben wir einen\u00a0gro\u00dfen Leiterschaftstag an deinem lokalen Campus \u2013 gef\u00fcllt mit Sessions von<\/p>\n<p><strong>PHIL &amp; LUCINDA DOOLEY.\u00a0<\/strong><\/p>\n<p>Wir glauben, dass dieser\u00a0Tag\u00a0ein unglaublicher Segen f\u00fcr jeden wird und w\u00fcrden uns freuen, dich dabei zu haben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Leider ist der Eintrag nur auf English verf\u00fcgbar.es ist wirklich eine unglaubliche Freude, mit dir zusammen Kirche zu bauen! Wir haben uns dieses Jahr mit unserem Leiterschaftstag im Januar und durch unsere Leadership Training Nights, dem Leben &amp; Leiterschafts Blog und anderen Inputs auf die Reise gemacht, zu besseren Leitern zu werden \u2013 damit Menschen [&hellip;]<\/p>\n","protected":false},"author":1394,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[283],"class_list":["post-420079","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-konstanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Leadership Day mit Dooleys[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Leider ist der Eintrag nur auf English verf\u00fcgbar.es ist wirklich eine unglaubliche Freude, mit dir zusammen Kirche zu bauen! Wir haben uns dieses Jahr mit unserem Leiterschaftstag im Januar und durch unsere Leadership Training Nights, dem Leben &amp; Leiterschafts Blog und anderen Inputs auf die Reise gemacht, zu besseren Leitern zu werden \u2013 damit Menschen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-15T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-14T00:00:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Leadership Day mit Dooleys\",\"datePublished\":\"2017-08-15T00:00:00+00:00\",\"dateModified\":\"2017-09-14T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\"},\"wordCount\":115,\"commentCount\":0,\"keywords\":[\"Konstanz\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\",\"url\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\",\"name\":\"[:en]Leadership Day mit Dooleys[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2017-08-15T00:00:00+00:00\",\"dateModified\":\"2017-09-14T00:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leadership Day mit Dooleys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/hillsong.com\/germany\/de\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Leadership Day mit Dooleys[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/","og_locale":"de_DE","og_type":"article","og_title":"[:en]Leadership Day mit Dooleys[:] - Dach","og_description":"Leider ist der Eintrag nur auf English verf\u00fcgbar.es ist wirklich eine unglaubliche Freude, mit dir zusammen Kirche zu bauen! Wir haben uns dieses Jahr mit unserem Leiterschaftstag im Januar und durch unsere Leadership Training Nights, dem Leben &amp; Leiterschafts Blog und anderen Inputs auf die Reise gemacht, zu besseren Leitern zu werden \u2013 damit Menschen [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/","og_site_name":"Dach","article_published_time":"2017-08-15T00:00:00+00:00","article_modified_time":"2017-09-14T00:00:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/"},"author":{"name":"","@id":""},"headline":"Leadership Day mit Dooleys","datePublished":"2017-08-15T00:00:00+00:00","dateModified":"2017-09-14T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/"},"wordCount":115,"commentCount":0,"keywords":["Konstanz"],"articleSection":["Uncategorized"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/","url":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/","name":"[:en]Leadership Day mit Dooleys[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2017-08-15T00:00:00+00:00","dateModified":"2017-09-14T00:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/de\/event\/2017\/08\/leadership-day-mit-dooleys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Leadership Day mit Dooleys"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"","url":"https:\/\/hillsong.com\/germany\/de\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/420079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/users\/1394"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/comments?post=420079"}],"version-history":[{"count":0,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/420079\/revisions"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/media?parent=420079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/categories?post=420079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/tags?post=420079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}