{"id":635690,"date":"2021-03-26T09:38:20","date_gmt":"2021-03-26T09:38:20","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=635690"},"modified":"2021-03-26T09:38:20","modified_gmt":"2021-03-26T09:38:20","slug":"easter-bible-study-day-7","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/de\/blog\/2021\/03\/easter-bible-study-day-7\/","title":{"rendered":"Ostern Bibelleseplan |\u00a0Tag 7"},"content":{"rendered":"<p><b>Die Perfektion der Liebe<\/b><\/p>\n<p><b>1. Johannes 4,18 (gem\u00e4\u00df Passion Translation)<\/b><\/p>\n<p><b>Liebe bringt niemals Angst, denn Angst ist immer mit Strafe verbunden. Aber die Vollkommenheit der Liebe vertreibt die Angst vor Strafe weit aus unseren Herzen. Wer st\u00e4ndig in Angst vor Strafe wandelt, hat die Vollkommenheit der Liebe nicht erreicht.<\/b><\/p>\n<p>Schau dich um in unserer Welt &#8211; Perfektionismus wird in ziemlich vielen Bereichen angestrebt. Ob Werbung, Job oder in unseren sozialen Beziehungen &#8211; unsere Gesellschaft trainiert uns, nach dem Neuen zu suchen, sobald uns das Alte langweilig wird oder nicht gut genug erscheint.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>In einer Welt, in der Perfektionismus angestrebt wird, ist es f\u00fcr manche umso schwerer sich einzugestehen, dass in dieser Welt nichts perfekt ist. Weder du noch ich. Nicht umsonst k\u00f6nnen wir im 1. Buch Mose nachlesen, dass Gott den Menschen erschuf und sah: Es war sehr gut (1. Mose 1:31 HFA). Nicht perfekt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Nichts ist perfekt, au\u00dfer Gottes Liebe zu dir.<br \/>\nWenn du sie empf\u00e4ngst, passiert etwas Gro\u00dfartiges: Du sp\u00fcrst inneren Frieden und die Liebe wird noch gr\u00f6\u00dfer.<br \/>\nDenn: Die Liebe ist das Einzige, das sich verdoppelt, wenn man es teilt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Die Liebe ist die gr\u00f6\u00dfte Macht. Sie ist st\u00e4rker, als jedes andere Gef\u00fchl. Sicher hast du schon einmal geliebt &#8211; deinen Partner oder deine Partnerin, deine Eltern, deine Geschwister oder einen guten Freund oder eine gute Freundin. So gro\u00df diese Liebe auch ist, sie reicht wohl noch lange nicht an Gottes Liebe zu dir heran.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Seine Liebe zu dir sieht \u00fcber Fehler hinweg. Sie steht \u00fcber allem (1. Korinther 13:13) und sollte deshalb immer das letzte Wort haben, selbst in Situationen, in denen es dir schwer f\u00e4llt. Hast du Gottes Liebe einmal erkannt und gesp\u00fcrt, welche Macht sie hat, befreit sie dich von jeglicher Angst. Wenn du dich f\u00fcrchtest, hast du Gottes Liebe noch nicht verstanden oder wahrhaftig angenommen.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Jemanden liebevoll behandeln, selbst wenn er andere oder dich schlecht behandelt? Das ist eine gro\u00dfe Herausforderung und aus eigener Kraft schwer umzusetzen. Aber Gott bef\u00e4higt dich dazu, wenn du ihn l\u00e4sst. Denn er gab sein eigenes Leben f\u00fcr dich, um deine S\u00fcnden auf sich zu nehmen. Aus Liebe zu dir.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Action Steps<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul>\n<li>Schreibe auf, was Gottes perfekte Liebe f\u00fcr dich pers\u00f6nlich bedeutet und wie du diese Liebe in deinem Umfeld ausleben kannst.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>Hat die Liebe in deinem Leben immer das letzte Wort? Pr\u00fcfe es und zeige diese Woche 3 Menschen deine Liebe.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<li>Lass Gott in Momenten der Angst und Verzweiflung die Kontrolle \u00fcbernehmen, wende dich an ihn, bete und erfahre seine unendliche, perfekte Liebe.<span class=\"Apple-converted-space\">\u00a0<\/span><\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Perfektion der Liebe 1. Johannes 4,18 (gem\u00e4\u00df Passion Translation) Liebe bringt niemals Angst, denn Angst ist immer mit Strafe verbunden. Aber die Vollkommenheit der Liebe vertreibt die Angst vor Strafe weit aus unseren Herzen. Wer st\u00e4ndig in Angst vor Strafe wandelt, hat die Vollkommenheit der Liebe nicht erreicht. Schau dich um in unserer Welt [&hellip;]<\/p>\n","protected":false},"author":51262,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-635690","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ostern Bibelleseplan |\u00a0Tag 7 - Dach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Easter Bible Study | Day 7[:de]Ostern Bibelleseplan |\u00a0Tag 7[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Die Perfektion der Liebe 1. Johannes 4,18 (gem\u00e4\u00df Passion Translation) Liebe bringt niemals Angst, denn Angst ist immer mit Strafe verbunden. Aber die Vollkommenheit der Liebe vertreibt die Angst vor Strafe weit aus unseren Herzen. Wer st\u00e4ndig in Angst vor Strafe wandelt, hat die Vollkommenheit der Liebe nicht erreicht. Schau dich um in unserer Welt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-26T09:38:20+00:00\" \/>\n<meta name=\"author\" content=\"Jenny Alloway\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenny Alloway\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\"},\"author\":{\"name\":\"Jenny Alloway\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"headline\":\"Ostern Bibelleseplan |\u00a0Tag 7\",\"datePublished\":\"2021-03-26T09:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\"},\"wordCount\":794,\"commentCount\":0,\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\",\"url\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\",\"name\":\"[:en]Easter Bible Study | Day 7[:de]Ostern Bibelleseplan |\u00a0Tag 7[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2021-03-26T09:38:20+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Easter Bible Study | Day 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\",\"name\":\"Jenny Alloway\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"caption\":\"Jenny Alloway\"},\"url\":\"https:\/\/hillsong.com\/germany\/de\/author\/jenny-alloway\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Easter Bible Study | Day 7[:de]Ostern Bibelleseplan |\u00a0Tag 7[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/","og_locale":"de_DE","og_type":"article","og_title":"[:en]Easter Bible Study | Day 7[:de]Ostern Bibelleseplan |\u00a0Tag 7[:] - Dach","og_description":"Die Perfektion der Liebe 1. Johannes 4,18 (gem\u00e4\u00df Passion Translation) Liebe bringt niemals Angst, denn Angst ist immer mit Strafe verbunden. Aber die Vollkommenheit der Liebe vertreibt die Angst vor Strafe weit aus unseren Herzen. Wer st\u00e4ndig in Angst vor Strafe wandelt, hat die Vollkommenheit der Liebe nicht erreicht. Schau dich um in unserer Welt [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/","og_site_name":"Dach","article_published_time":"2021-03-26T09:38:20+00:00","author":"Jenny Alloway","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jenny Alloway","Est. reading time":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/"},"author":{"name":"Jenny Alloway","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"headline":"Ostern Bibelleseplan |\u00a0Tag 7","datePublished":"2021-03-26T09:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/"},"wordCount":794,"commentCount":0,"articleSection":["Uncategorized"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/","url":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/","name":"[:en]Easter Bible Study | Day 7[:de]Ostern Bibelleseplan |\u00a0Tag 7[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2021-03-26T09:38:20+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/blog\/2021\/03\/easter-bible-study-day-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Easter Bible Study | Day 7"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b","name":"Jenny Alloway","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","caption":"Jenny Alloway"},"url":"https:\/\/hillsong.com\/germany\/de\/author\/jenny-alloway\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/635690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/users\/51262"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/comments?post=635690"}],"version-history":[{"count":1,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/635690\/revisions"}],"predecessor-version":[{"id":635694,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/635690\/revisions\/635694"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/media?parent=635690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/categories?post=635690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/tags?post=635690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}