{"id":632565,"date":"2020-10-21T12:14:06","date_gmt":"2020-10-21T12:14:06","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=632565"},"modified":"2020-11-17T10:49:05","modified_gmt":"2020-11-17T10:49:05","slug":"micro-church-11","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/","title":{"rendered":"MICRO CHURCH | 10 UHR"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/hillsong.com\/germany\/en\/wp-json\/wp\/v2\/posts\/632565\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> y <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/632565\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p><\/strong>Wir feiern Micro Church!<\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben.<br \/>\nWir treffen uns in Gruppen ab 30+ Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English y Deutsch.Wir feiern Micro Church! Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben. Wir treffen uns in Gruppen [&hellip;]<\/p>\n","protected":false},"author":53999,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[273,14965,271],"tags":[285],"class_list":["post-632565","post","type-post","status-publish","format-standard","hentry","category-dusseldorf","category-events-germany","category-germany","tag-dusseldorf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MICRO CHURCH | 10 UHR - Dach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MICRO CHURCH | 10 UHR - Dach\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English y Deutsch.Wir feiern Micro Church! Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben. Wir treffen uns in Gruppen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T12:14:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-17T10:49:05+00:00\" \/>\n<meta name=\"author\" content=\"Elisabeth Strack\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisabeth Strack\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\"},\"author\":{\"name\":\"Elisabeth Strack\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc\"},\"headline\":\"MICRO CHURCH | 10 UHR\",\"datePublished\":\"2020-10-21T12:14:06+00:00\",\"dateModified\":\"2020-11-17T10:49:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\"},\"wordCount\":164,\"commentCount\":0,\"keywords\":[\"Dusseldorf\"],\"articleSection\":[\"Dusseldorf\",\"Events\",\"Germany\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\",\"url\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\",\"name\":\"MICRO CHURCH | 10 UHR - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2020-10-21T12:14:06+00:00\",\"dateModified\":\"2020-11-17T10:49:05+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MICRO CHURCH | 10 UHR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc\",\"name\":\"Elisabeth Strack\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g\",\"caption\":\"Elisabeth Strack\"},\"url\":\"https:\/\/hillsong.com\/germany\/es\/author\/elisabeth-strack\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MICRO CHURCH | 10 UHR - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/","og_locale":"es_ES","og_type":"article","og_title":"MICRO CHURCH | 10 UHR - Dach","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English y Deutsch.Wir feiern Micro Church! Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben. Wir treffen uns in Gruppen [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/","og_site_name":"Dach","article_published_time":"2020-10-21T12:14:06+00:00","article_modified_time":"2020-11-17T10:49:05+00:00","author":"Elisabeth Strack","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Elisabeth Strack","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/"},"author":{"name":"Elisabeth Strack","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc"},"headline":"MICRO CHURCH | 10 UHR","datePublished":"2020-10-21T12:14:06+00:00","dateModified":"2020-11-17T10:49:05+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/"},"wordCount":164,"commentCount":0,"keywords":["Dusseldorf"],"articleSection":["Dusseldorf","Events","Germany"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/","url":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/","name":"MICRO CHURCH | 10 UHR - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2020-10-21T12:14:06+00:00","dateModified":"2020-11-17T10:49:05+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2020\/10\/micro-church-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"MICRO CHURCH | 10 UHR"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/758598958e0c67d51bf1abf176000efc","name":"Elisabeth Strack","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a22b08b3c1ecfcc06852792db0067e633d9227ed0ee6d9f811f3e204f917ec29?s=96&d=mm&r=g","caption":"Elisabeth Strack"},"url":"https:\/\/hillsong.com\/germany\/es\/author\/elisabeth-strack\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/posts\/632565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/users\/53999"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/comments?post=632565"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/posts\/632565\/revisions"}],"predecessor-version":[{"id":633134,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/posts\/632565\/revisions\/633134"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/media?parent=632565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/categories?post=632565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/es\/wp-json\/wp\/v2\/tags?post=632565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}