{"id":291840,"date":"2016-11-02T00:00:00","date_gmt":"2016-11-02T00:00:00","guid":{"rendered":"http:\/\/hillsong.com\/?p=291840"},"modified":"2016-11-02T00:00:00","modified_gmt":"2016-11-02T00:00:00","slug":"sisterhood-united-night-in-duesseldorf","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/fr\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/","title":{"rendered":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF"},"content":{"rendered":"<hr \/>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\">| am <strong>26.11<\/strong> in D\u00fcsseldorf\u00a0|<\/span><\/p>\n<hr \/>\n<div><\/div>\n<div><span style=\"color: #ffffff;\">\u00a0&#8230;<\/span><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #333333;\">Du bist herzlich eingeladen!<\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">\u00a0 \u00a0 \u00a0 \u00a0Schlie\u00dfe dich hunderten von Frauen aller Altersgruppen und Hintergr\u00fcnde an, <\/span><span style=\"color: #333333;\">die sich unter einem Dach versammeln und in Einheit stehen, um eine Botschaft\u00a0f\u00fcr eine Zeit wie diese\u00a0von Pastor Bobbie Houston zu h\u00f6ren. Lasst uns gemeinsam dazu beitragen, die Atmosph\u00e4re unserer lokalen und globalen Welt mit Lobpreis, Gebet und Freundlichkeit zu erf\u00fcllen.<\/span><br \/>\n<span style=\"color: #333333;\"> Wie Pastorin Bobbie sagt: \u201e<em>&#8216;Das Fl\u00fcstern&#8217;<\/em>\u00a0ist pers\u00f6nlich. Es fl\u00fcstert\u00a0<em>&#8216;lass dich finden&#8217;<\/em> \u2013 lass dich in seiner Liebe, seiner Weisheit und G\u00fcte, in seinem Frieden und seiner Bestimmung finden. Lass dich finden, sodass andere durch dich Hoffnung finden k\u00f6nnen.\u201c <\/span><span style=\"color: #333333;\">Unser Zusammenkommen wird ein Segen f\u00fcr dich sein und f\u00fcr diejenigen, die durch dein Leben ber\u00fchrt werden.<\/span><\/p>\n<p><span style=\"color: #333333;\">Alles Liebe<\/span><br \/>\n<span style=\"color: #333333;\"> Joanna Haverkamp<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>| am 26.11 in D\u00fcsseldorf\u00a0| \u00a0&#8230; Du bist herzlich eingeladen! \u00a0 \u00a0 \u00a0 \u00a0Schlie\u00dfe dich hunderten von Frauen aller Altersgruppen und Hintergr\u00fcnde an, die sich unter einem Dach versammeln und in Einheit stehen, um eine Botschaft\u00a0f\u00fcr eine Zeit wie diese\u00a0von Pastor Bobbie Houston zu h\u00f6ren. Lasst uns gemeinsam dazu beitragen, die Atmosph\u00e4re unserer lokalen und [&hellip;]<\/p>\n","protected":false},"author":1394,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-291840","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach\" \/>\n<meta property=\"og:description\" content=\"| am 26.11 in D\u00fcsseldorf\u00a0| \u00a0&#8230; Du bist herzlich eingeladen! \u00a0 \u00a0 \u00a0 \u00a0Schlie\u00dfe dich hunderten von Frauen aller Altersgruppen und Hintergr\u00fcnde an, die sich unter einem Dach versammeln und in Einheit stehen, um eine Botschaft\u00a0f\u00fcr eine Zeit wie diese\u00a0von Pastor Bobbie Houston zu h\u00f6ren. Lasst uns gemeinsam dazu beitragen, die Atmosph\u00e4re unserer lokalen und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T00:00:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF\",\"datePublished\":\"2016-11-02T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\"},\"wordCount\":141,\"commentCount\":0,\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\",\"url\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\",\"name\":\"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2016-11-02T00:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/","og_locale":"fr_FR","og_type":"article","og_title":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach","og_description":"| am 26.11 in D\u00fcsseldorf\u00a0| \u00a0&#8230; Du bist herzlich eingeladen! \u00a0 \u00a0 \u00a0 \u00a0Schlie\u00dfe dich hunderten von Frauen aller Altersgruppen und Hintergr\u00fcnde an, die sich unter einem Dach versammeln und in Einheit stehen, um eine Botschaft\u00a0f\u00fcr eine Zeit wie diese\u00a0von Pastor Bobbie Houston zu h\u00f6ren. Lasst uns gemeinsam dazu beitragen, die Atmosph\u00e4re unserer lokalen und [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/","og_site_name":"Dach","article_published_time":"2016-11-02T00:00:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/"},"author":{"name":"","@id":""},"headline":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF","datePublished":"2016-11-02T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/"},"wordCount":141,"commentCount":0,"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/","url":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/","name":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2016-11-02T00:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/event\/2016\/11\/sisterhood-united-night-in-duesseldorf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"SISTERHOOD \u2013 UNITED NIGHT IN D\u00dcSSELDORF"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"","url":"https:\/\/hillsong.com\/germany\/fr\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts\/291840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/users\/1394"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/comments?post=291840"}],"version-history":[{"count":0,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts\/291840\/revisions"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/media?parent=291840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/categories?post=291840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/tags?post=291840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}