{"id":412956,"date":"2017-06-28T00:00:00","date_gmt":"2017-06-28T00:00:00","guid":{"rendered":"https:\/\/hillsong.com\/?p=412956"},"modified":"2017-07-03T00:00:00","modified_gmt":"2017-07-03T00:00:00","slug":"familien-sommerfest","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/fr\/event\/2017\/06\/familien-sommerfest\/","title":{"rendered":"Familien Sommerfest"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/hillsong.com\/germany\/en\/wp-json\/wp\/v2\/posts\/412956\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> et <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/412956\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>Alle Familien treffen sich zum gemeinsamen Grillen und Tr\u00f6delmarkt im Hub, um die Sommerferien einzuleiten. Die Kids werden viel Spa\u00df haben und f\u00fcr die Eltern gibt es einen Input zum Thema \u201cElternschaft\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en English et Deutsch.Alle Familien treffen sich zum gemeinsamen Grillen und Tr\u00f6delmarkt im Hub, um die Sommerferien einzuleiten. Die Kids werden viel Spa\u00df haben und f\u00fcr die Eltern gibt es einen Input zum Thema \u201cElternschaft\u201d<\/p>\n","protected":false},"author":1394,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[285],"class_list":["post-412956","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-dusseldorf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Familien Sommerfest[:de]Familien Sommerfest[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"D\u00e9sol\u00e9, cet article est seulement disponible en English et Deutsch.Alle Familien treffen sich zum gemeinsamen Grillen und Tr\u00f6delmarkt im Hub, um die Sommerferien einzuleiten. Die Kids werden viel Spa\u00df haben und f\u00fcr die Eltern gibt es einen Input zum Thema \u201cElternschaft\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-28T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-03T00:00:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Familien Sommerfest\",\"datePublished\":\"2017-06-28T00:00:00+00:00\",\"dateModified\":\"2017-07-03T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\"},\"wordCount\":76,\"commentCount\":0,\"keywords\":[\"Dusseldorf\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\",\"url\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\",\"name\":\"[:en]Familien Sommerfest[:de]Familien Sommerfest[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2017-06-28T00:00:00+00:00\",\"dateModified\":\"2017-07-03T00:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familien Sommerfest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Familien Sommerfest[:de]Familien Sommerfest[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/","og_locale":"fr_FR","og_type":"article","og_title":"[:en]Familien Sommerfest[:de]Familien Sommerfest[:] - Dach","og_description":"D\u00e9sol\u00e9, cet article est seulement disponible en English et Deutsch.Alle Familien treffen sich zum gemeinsamen Grillen und Tr\u00f6delmarkt im Hub, um die Sommerferien einzuleiten. Die Kids werden viel Spa\u00df haben und f\u00fcr die Eltern gibt es einen Input zum Thema \u201cElternschaft\u201d","og_url":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/","og_site_name":"Dach","article_published_time":"2017-06-28T00:00:00+00:00","article_modified_time":"2017-07-03T00:00:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/"},"author":{"name":"","@id":""},"headline":"Familien Sommerfest","datePublished":"2017-06-28T00:00:00+00:00","dateModified":"2017-07-03T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/"},"wordCount":76,"commentCount":0,"keywords":["Dusseldorf"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/","url":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/","name":"[:en]Familien Sommerfest[:de]Familien Sommerfest[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2017-06-28T00:00:00+00:00","dateModified":"2017-07-03T00:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/es\/event\/2017\/06\/familien-sommerfest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Familien Sommerfest"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"","url":"https:\/\/hillsong.com\/germany\/fr\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts\/412956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/users\/1394"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/comments?post=412956"}],"version-history":[{"count":0,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/posts\/412956\/revisions"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/media?parent=412956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/categories?post=412956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/fr\/wp-json\/wp\/v2\/tags?post=412956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}