{"id":627756,"date":"2020-07-15T00:00:00","date_gmt":"2020-07-15T00:00:00","guid":{"rendered":"https:\/\/hillsong.com\/?p=627756"},"modified":"2020-07-16T00:00:00","modified_gmt":"2020-07-16T00:00:00","slug":"wanderung-zum-kloster-andechs-mit-besuch-im-biergarten","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/id\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/","title":{"rendered":"Wanderung zum Kloster Andechs mit Besuch im Biergarten"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-id\">Maaf, entri ini hanya tersedia di <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/627756\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>Wir wandern gemeinsam zum Kloster Andechs und besuchen dort den sch\u00f6nen Biergarten. Jeder ist eingeladen!<\/p>\n<p>Treffpunkt ist um 15 Uhr bei der S8-Bahn Station Herrsching<\/p>","protected":false},"excerpt":{"rendered":"<p>Maaf, entri ini hanya tersedia di Deutsch.Wir wandern gemeinsam zum Kloster Andechs und besuchen dort den sch\u00f6nen Biergarten. Jeder ist eingeladen! Treffpunkt ist um 15 Uhr bei der S8-Bahn Station Herrsching<\/p>\n","protected":false},"author":53840,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15031,271,15030],"tags":[14779,14778],"class_list":["post-627756","post","type-post","status-publish","format-standard","hentry","category-events-munich","category-germany","category-munich","tag-muenchen","tag-munich"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]Wanderung zum Kloster Andechs mit Besuch im Biergarten[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Maaf, entri ini hanya tersedia di Deutsch.Wir wandern gemeinsam zum Kloster Andechs und besuchen dort den sch\u00f6nen Biergarten. Jeder ist eingeladen! Treffpunkt ist um 15 Uhr bei der S8-Bahn Station Herrsching\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-16T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Leonie Schaebler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonie Schaebler\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\"},\"author\":{\"name\":\"Leonie Schaebler\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54\"},\"headline\":\"Wanderung zum Kloster Andechs mit Besuch im Biergarten\",\"datePublished\":\"2020-07-15T00:00:00+00:00\",\"dateModified\":\"2020-07-16T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\"},\"wordCount\":36,\"keywords\":[\"m\u00fcnchen\",\"munich\"],\"articleSection\":[\"Events\",\"Germany\",\"Munich\"],\"inLanguage\":\"id-ID\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\",\"url\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\",\"name\":\"[:de]Wanderung zum Kloster Andechs mit Besuch im Biergarten[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2020-07-15T00:00:00+00:00\",\"dateModified\":\"2020-07-16T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#breadcrumb\"},\"inLanguage\":\"id-ID\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wanderung zum Kloster Andechs mit Besuch im Biergarten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id-ID\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54\",\"name\":\"Leonie Schaebler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id-ID\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g\",\"caption\":\"Leonie Schaebler\"},\"url\":\"https:\/\/hillsong.com\/germany\/id\/author\/leonie-schaebler\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]Wanderung zum Kloster Andechs mit Besuch im Biergarten[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/","og_locale":"id_ID","og_type":"article","og_title":"[:de]Wanderung zum Kloster Andechs mit Besuch im Biergarten[:] - Dach","og_description":"Maaf, entri ini hanya tersedia di Deutsch.Wir wandern gemeinsam zum Kloster Andechs und besuchen dort den sch\u00f6nen Biergarten. Jeder ist eingeladen! Treffpunkt ist um 15 Uhr bei der S8-Bahn Station Herrsching","og_url":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/","og_site_name":"Dach","article_published_time":"2020-07-15T00:00:00+00:00","article_modified_time":"2020-07-16T00:00:00+00:00","author":"Leonie Schaebler","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Leonie Schaebler"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/"},"author":{"name":"Leonie Schaebler","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54"},"headline":"Wanderung zum Kloster Andechs mit Besuch im Biergarten","datePublished":"2020-07-15T00:00:00+00:00","dateModified":"2020-07-16T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/"},"wordCount":36,"keywords":["m\u00fcnchen","munich"],"articleSection":["Events","Germany","Munich"],"inLanguage":"id-ID"},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/","url":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/","name":"[:de]Wanderung zum Kloster Andechs mit Besuch im Biergarten[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2020-07-15T00:00:00+00:00","dateModified":"2020-07-16T00:00:00+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#breadcrumb"},"inLanguage":"id-ID","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/07\/wanderung-zum-kloster-andechs-mit-besuch-im-biergarten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Wanderung zum Kloster Andechs mit Besuch im Biergarten"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id-ID"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/d328cc3fbf7b0085075874abf04f8b54","name":"Leonie Schaebler","image":{"@type":"ImageObject","inLanguage":"id-ID","@id":"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2add05afe29c9150ca9c3850fa0b2a531258c98e4782837b34ab5404aeb2ced?s=96&d=mm&r=g","caption":"Leonie Schaebler"},"url":"https:\/\/hillsong.com\/germany\/id\/author\/leonie-schaebler\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts\/627756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/users\/53840"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/comments?post=627756"}],"version-history":[{"count":0,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts\/627756\/revisions"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/media?parent=627756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/categories?post=627756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/tags?post=627756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}