{"id":633198,"date":"2020-11-19T09:05:54","date_gmt":"2020-11-19T09:05:54","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=633198"},"modified":"2020-11-19T09:05:54","modified_gmt":"2020-11-19T09:05:54","slug":"kreuzlingen-das-troesch-micro-church-22-11","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/id\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/","title":{"rendered":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-id\">Maaf, entri ini hanya tersedia di <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/633198\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>WILLKOMMEN ZU MICRO CHURCH<\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben.  Wir treffen uns in Gruppen ab 30+ Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Maaf, entri ini hanya tersedia di Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen wir eine neue [&hellip;]<\/p>\n","protected":false},"author":51263,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15403,271,272],"tags":[283],"class_list":["post-633198","post","type-post","status-publish","format-standard","hentry","category-events-konstanz","category-germany","category-konstanz","tag-konstanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Maaf, entri ini hanya tersedia di Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen wir eine neue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T09:05:54+00:00\" \/>\n<meta name=\"author\" content=\"Tabea Grimm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tabea Grimm\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\"},\"author\":{\"name\":\"Tabea Grimm\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"headline\":\"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.\",\"datePublished\":\"2020-11-19T09:05:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\"},\"wordCount\":95,\"commentCount\":0,\"keywords\":[\"Konstanz\"],\"articleSection\":[\"Events\",\"Germany\",\"Konstanz\"],\"inLanguage\":\"id-ID\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\",\"url\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\",\"name\":\"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2020-11-19T09:05:54+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#breadcrumb\"},\"inLanguage\":\"id-ID\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id-ID\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\",\"name\":\"Tabea Grimm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id-ID\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"caption\":\"Tabea Grimm\"},\"url\":\"https:\/\/hillsong.com\/germany\/id\/author\/tabea-grimm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/","og_locale":"id_ID","og_type":"article","og_title":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.[:] - Dach","og_description":"Maaf, entri ini hanya tersedia di Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen wir eine neue [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/","og_site_name":"Dach","article_published_time":"2020-11-19T09:05:54+00:00","author":"Tabea Grimm","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tabea Grimm"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/"},"author":{"name":"Tabea Grimm","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"headline":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.","datePublished":"2020-11-19T09:05:54+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/"},"wordCount":95,"commentCount":0,"keywords":["Konstanz"],"articleSection":["Events","Germany","Konstanz"],"inLanguage":"id-ID","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/","url":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/","name":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11.[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2020-11-19T09:05:54+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#breadcrumb"},"inLanguage":"id-ID","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/kreuzlingen-das-troesch-micro-church-22-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 22.11."}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id-ID"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790","name":"Tabea Grimm","image":{"@type":"ImageObject","inLanguage":"id-ID","@id":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","caption":"Tabea Grimm"},"url":"https:\/\/hillsong.com\/germany\/id\/author\/tabea-grimm\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts\/633198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/users\/51263"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/comments?post=633198"}],"version-history":[{"count":1,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts\/633198\/revisions"}],"predecessor-version":[{"id":633199,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/posts\/633198\/revisions\/633199"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/media?parent=633198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/categories?post=633198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/id\/wp-json\/wp\/v2\/tags?post=633198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}