{"id":634285,"date":"2021-01-31T07:41:27","date_gmt":"2021-01-31T07:41:27","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=634285"},"modified":"2021-01-31T07:41:27","modified_gmt":"2021-01-31T07:41:27","slug":"kreuzlingen-tagerwilen-7-2","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/it\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/","title":{"rendered":"KREUZLINGEN, T\u00c4GERWILEN | 7.2."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-it\">Ci spiace, ma questo articolo \u00e8 disponibile soltanto in <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/634285\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p><strong>WILLKOMMEN ZU MICRO CHURCH <\/strong><\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil von unserem Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben. Wir treffen uns in Gruppen ab 30+ Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<\/p>\n<p><strong>MEDIZINISCHE MASKENPFLICHT:<\/strong> Ab sofort gilt in unseren Gottesdiensten die Pflicht, medizinische Masken zu tragen, dazu geh\u00f6ren OP-Masken, FFP2-Masken und Masken des Typs KN95.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ci spiace, ma questo articolo \u00e8 disponibile soltanto in Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]<\/p>\n","protected":false},"author":54092,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15403,271,272],"tags":[283],"class_list":["post-634285","post","type-post","status-publish","format-standard","hentry","category-events-konstanz","category-germany","category-konstanz","tag-konstanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]KREUZLINGEN, T\u00c4GERWILEN | 7.2.[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Ci spiace, ma questo articolo \u00e8 disponibile soltanto in Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-31T07:41:27+00:00\" \/>\n<meta name=\"author\" content=\"viannemueller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"viannemueller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\"},\"author\":{\"name\":\"viannemueller\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f\"},\"headline\":\"KREUZLINGEN, T\u00c4GERWILEN | 7.2.\",\"datePublished\":\"2021-01-31T07:41:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\"},\"wordCount\":118,\"commentCount\":0,\"keywords\":[\"Konstanz\"],\"articleSection\":[\"Events\",\"Germany\",\"Konstanz\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\",\"url\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\",\"name\":\"[:de]KREUZLINGEN, T\u00c4GERWILEN | 7.2.[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2021-01-31T07:41:27+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KREUZLINGEN, T\u00c4GERWILEN | 7.2.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f\",\"name\":\"viannemueller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g\",\"caption\":\"viannemueller\"},\"url\":\"https:\/\/hillsong.com\/germany\/it\/author\/viannemueller\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 7.2.[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/","og_locale":"it_IT","og_type":"article","og_title":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 7.2.[:] - Dach","og_description":"Ci spiace, ma questo articolo \u00e8 disponibile soltanto in Deutsch.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH schaffen [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/","og_site_name":"Dach","article_published_time":"2021-01-31T07:41:27+00:00","author":"viannemueller","twitter_card":"summary_large_image","twitter_misc":{"Written by":"viannemueller","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/"},"author":{"name":"viannemueller","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f"},"headline":"KREUZLINGEN, T\u00c4GERWILEN | 7.2.","datePublished":"2021-01-31T07:41:27+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/"},"wordCount":118,"commentCount":0,"keywords":["Konstanz"],"articleSection":["Events","Germany","Konstanz"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/","url":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/","name":"[:de]KREUZLINGEN, T\u00c4GERWILEN | 7.2.[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2021-01-31T07:41:27+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/ua\/event\/2021\/01\/kreuzlingen-tagerwilen-7-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"KREUZLINGEN, T\u00c4GERWILEN | 7.2."}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/4d79936bcb986fce878da148effe347f","name":"viannemueller","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6ced4fab99176860fef160d431d5f0fef101d2f7249981f8b4db06c6b0c69f1?s=96&d=mm&r=g","caption":"viannemueller"},"url":"https:\/\/hillsong.com\/germany\/it\/author\/viannemueller\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/posts\/634285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/users\/54092"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/comments?post=634285"}],"version-history":[{"count":1,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/posts\/634285\/revisions"}],"predecessor-version":[{"id":634286,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/posts\/634285\/revisions\/634286"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/media?parent=634285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/categories?post=634285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/it\/wp-json\/wp\/v2\/tags?post=634285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}