{"id":634295,"date":"2021-02-02T13:00:11","date_gmt":"2021-02-02T13:00:11","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=634295"},"modified":"2021-02-02T13:04:50","modified_gmt":"2021-02-02T13:04:50","slug":"collected","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/","title":{"rendered":"Eine Verpflichtung zu Exzellenz und Rechtschaffenheit"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-nl\">Onze verontschuldigingen, dit bericht is alleen beschikbaar in het <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/634295\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>38 Jahre im Dienst. Millionen von Menschen weltweit erreicht. Unsere Verpflichtung zu Exzellenz und Integrit\u00e4t ist nie ins Wanken geraten und wird sich nie \u00e4ndern. Trotz einer Pandemie, trotz aller Widerst\u00e4nde sind wir zuversichtlicher denn je, dass Gott Gro\u00dfes vorhat. Wir lieben euch.<\/p>\n<p>Wir stehen in Ehrfurcht. Wir stehen in Ehrfurcht vor dem, was Gott durch Hillsong Church schreibt. Vom &#8220;JA&#8221; unserer Pastoren Brian und Bobbie Houston zum Start von Hillsong im Jahr 1983. Bis hin zu der unglaublichen Musik, die sch\u00e4tzungsweise von 50 Millionen Menschen in 60 Sprachen rund um die Welt jede Woche gesungen wird. Weiter zu den Hillsong-Churches in 30 L\u00e4ndern auf sechs Kontinenten. Auf die fast 20.000 Studenten, die das Hillsong College absolviert haben. Zum Hillsong Channel, der 24 Stunden am Tag, sieben Tage die Woche sendet und Hoffnung in die Welt bringt. Auf den unermesslichen Einfluss der sozialen Gerechtigkeitsarbeit von Hillsong durch CityCare und Because We Can, sowohl lokal als auch global. Auf die Sisterhood, die weltweit Hunderttausende von Frauen in Christus und dem Auftrag vereint hat. Auf jedes einzelne Leben, das durch den treuen Dienst der Hillsong Church in Jesus erl\u00f6st und wiederhergestellt worden ist. Wir stehen in Ehrfurcht.<\/p>\n<p>Wir bleiben unersch\u00fctterlich. Wir sind unersch\u00fctterlich in unserer Vision, im Gebet Millionen auf der ganzen Erde f\u00fcr Christus zu erreichen. Eine Kirche zu sein, die jeden Mann, jede Frau und jedes Kind, das durch die T\u00fcren geht, mit Liebe und bewusster F\u00fcrsorge, die das Reich Gottes vorlebt, &#8220;zuhause&#8221; willkommen hei\u00dft. Leidenschaftliche Anbetung mit neuen und alten Liedern, die Generationen f\u00fcr Jesus formen. Konstant und konsequent innovativ zu sein. Junge Leiter zu erziehen, auszur\u00fcsten und zu bef\u00e4higen, die f\u00fcr die Aufgabe des Reiches Gottes gesalbt sind. Die Ressourcen, die uns gegeben wurden, so zu verwalten, dass unsere 38-j\u00e4hrige Geschichte von hervorragender finanzieller Verantwortung und Integrit\u00e4t auf der ganzen Welt hervorgehoben wird. Zu einer Leitung, die sich f\u00fcr Authentizit\u00e4t, Glaubw\u00fcrdigkeit und die Qualit\u00e4t des Herzens einsetzt. Wir bauen ein Netzwerk auf, das Pastoren und Leiter weltweit verbindet, damit sie beim Bau Seiner herrlichen Kirche aufbl\u00fchen. Die Kirche zu sein, die sich verpflichtet, die Liebe und Hoffnung Christi in unm\u00f6gliche Situationen zu bringen&#8221;. Wir bleiben unersch\u00fctterlich.<\/p>\n<p>Wir sind erwartungsvoll. Zweifellos waren die letzten Monate herausfordernd, aber Gott schreibt weiterhin eine unglaubliche Geschichte durch die Hillsong Church. Es gibt noch viele Kapitel, die geschrieben werden m\u00fcssen, und was Er schreibt, ist immer au\u00dfergew\u00f6hnlich. Wir sind in Erwartung von Wundern und Wundern, die auf Gottes Herrlichkeit und Macht hinweisen. Um zu sehen, wie Ketten fallen, Menschen wiederhergestellt werden, Gerechtigkeit und Heilung, Hoffnung und Vers\u00f6hnung kommen wird. Um den Ruf Gottes \u00fcber unseren Dienst gemeinsam mit euch in gro\u00dfer Freude, Liebe f\u00fcr alle und in wundersch\u00f6ner Hingabe auszuleben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Onze verontschuldigingen, dit bericht is alleen beschikbaar in het Deutsch.38 Jahre im Dienst. Millionen von Menschen weltweit erreicht. Unsere Verpflichtung zu Exzellenz und Integrit\u00e4t ist nie ins Wanken geraten und wird sich nie \u00e4ndern. Trotz einer Pandemie, trotz aller Widerst\u00e4nde sind wir zuversichtlicher denn je, dass Gott Gro\u00dfes vorhat. Wir lieben euch. Wir stehen in [&hellip;]<\/p>\n","protected":false},"author":51262,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-634295","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]Eine Verpflichtung zu Exzellenz und Rechtschaffenheit[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Onze verontschuldigingen, dit bericht is alleen beschikbaar in het Deutsch.38 Jahre im Dienst. Millionen von Menschen weltweit erreicht. Unsere Verpflichtung zu Exzellenz und Integrit\u00e4t ist nie ins Wanken geraten und wird sich nie \u00e4ndern. Trotz einer Pandemie, trotz aller Widerst\u00e4nde sind wir zuversichtlicher denn je, dass Gott Gro\u00dfes vorhat. Wir lieben euch. Wir stehen in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-02T13:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-02T13:04:50+00:00\" \/>\n<meta name=\"author\" content=\"Jenny Alloway\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenny Alloway\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\"},\"author\":{\"name\":\"Jenny Alloway\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"headline\":\"Eine Verpflichtung zu Exzellenz und Rechtschaffenheit\",\"datePublished\":\"2021-02-02T13:00:11+00:00\",\"dateModified\":\"2021-02-02T13:04:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\"},\"wordCount\":480,\"commentCount\":0,\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\",\"url\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\",\"name\":\"[:de]Eine Verpflichtung zu Exzellenz und Rechtschaffenheit[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2021-02-02T13:00:11+00:00\",\"dateModified\":\"2021-02-02T13:04:50+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine Verpflichtung zu Exzellenz und Rechtschaffenheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\",\"name\":\"Jenny Alloway\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"caption\":\"Jenny Alloway\"},\"url\":\"https:\/\/hillsong.com\/germany\/nl\/author\/jenny-alloway\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]Eine Verpflichtung zu Exzellenz und Rechtschaffenheit[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/","og_locale":"nl_NL","og_type":"article","og_title":"[:de]Eine Verpflichtung zu Exzellenz und Rechtschaffenheit[:] - Dach","og_description":"Onze verontschuldigingen, dit bericht is alleen beschikbaar in het Deutsch.38 Jahre im Dienst. Millionen von Menschen weltweit erreicht. Unsere Verpflichtung zu Exzellenz und Integrit\u00e4t ist nie ins Wanken geraten und wird sich nie \u00e4ndern. Trotz einer Pandemie, trotz aller Widerst\u00e4nde sind wir zuversichtlicher denn je, dass Gott Gro\u00dfes vorhat. Wir lieben euch. Wir stehen in [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/","og_site_name":"Dach","article_published_time":"2021-02-02T13:00:11+00:00","article_modified_time":"2021-02-02T13:04:50+00:00","author":"Jenny Alloway","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jenny Alloway","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/"},"author":{"name":"Jenny Alloway","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"headline":"Eine Verpflichtung zu Exzellenz und Rechtschaffenheit","datePublished":"2021-02-02T13:00:11+00:00","dateModified":"2021-02-02T13:04:50+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/"},"wordCount":480,"commentCount":0,"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/","url":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/","name":"[:de]Eine Verpflichtung zu Exzellenz und Rechtschaffenheit[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2021-02-02T13:00:11+00:00","dateModified":"2021-02-02T13:04:50+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/nl\/blog\/2021\/02\/collected\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Eine Verpflichtung zu Exzellenz und Rechtschaffenheit"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b","name":"Jenny Alloway","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","caption":"Jenny Alloway"},"url":"https:\/\/hillsong.com\/germany\/nl\/author\/jenny-alloway\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/posts\/634295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/users\/51262"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/comments?post=634295"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/posts\/634295\/revisions"}],"predecessor-version":[{"id":634302,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/posts\/634295\/revisions\/634302"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/media?parent=634295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/categories?post=634295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/nl\/wp-json\/wp\/v2\/tags?post=634295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}