{"id":633029,"date":"2020-11-01T07:42:11","date_gmt":"2020-11-01T07:42:11","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=633029"},"modified":"2020-11-01T07:42:11","modified_gmt":"2020-11-01T07:42:11","slug":"kreuzlingen-das-trosch-micro-church-8-11","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/no\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/","title":{"rendered":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-no\">Beklager, denne oppf\u00f8ringen er bare tilgjengelig i% LANG:, : og %.<\/p><p>WILLKOMMEN ZU MICRO CHURCH<\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben.  Wir treffen uns in Gruppen ab 30+ Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Beklager, denne oppf\u00f8ringen er bare tilgjengelig i% LANG:, : og %.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH [&hellip;]<\/p>\n","protected":false},"author":51263,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15403,271,272],"tags":[283],"class_list":["post-633029","post","type-post","status-publish","format-standard","hentry","category-events-konstanz","category-germany","category-konstanz","tag-konstanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Beklager, denne oppf\u00f8ringen er bare tilgjengelig i% LANG:, : og %.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-01T07:42:11+00:00\" \/>\n<meta name=\"author\" content=\"Tabea Grimm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tabea Grimm\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\"},\"author\":{\"name\":\"Tabea Grimm\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"headline\":\"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.\",\"datePublished\":\"2020-11-01T07:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\"},\"wordCount\":95,\"commentCount\":0,\"keywords\":[\"Konstanz\"],\"articleSection\":[\"Events\",\"Germany\",\"Konstanz\"],\"inLanguage\":\"no-NO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\",\"url\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\",\"name\":\"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2020-11-01T07:42:11+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#breadcrumb\"},\"inLanguage\":\"no-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"no-NO\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790\",\"name\":\"Tabea Grimm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"no-NO\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g\",\"caption\":\"Tabea Grimm\"},\"url\":\"https:\/\/hillsong.com\/germany\/no\/author\/tabea-grimm\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/","og_locale":"en_US","og_type":"article","og_title":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.[:] - Dach","og_description":"Beklager, denne oppf\u00f8ringen er bare tilgjengelig i% LANG:, : og %.WILLKOMMEN ZU MICRO CHURCH Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre. Mit MICRO CHURCH [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/","og_site_name":"Dach","article_published_time":"2020-11-01T07:42:11+00:00","author":"Tabea Grimm","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tabea Grimm"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/"},"author":{"name":"Tabea Grimm","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"headline":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.","datePublished":"2020-11-01T07:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/"},"wordCount":95,"commentCount":0,"keywords":["Konstanz"],"articleSection":["Events","Germany","Konstanz"],"inLanguage":"no-NO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/","url":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/","name":"[:de]KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11.[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2020-11-01T07:42:11+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#breadcrumb"},"inLanguage":"no-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/da\/event\/2020\/11\/kreuzlingen-das-trosch-micro-church-8-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"KREUZLINGEN DAS TR\u00d6SCH | MICRO CHURCH 8.11."}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"no-NO"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/e43cc03008cdeea1350273d0463f2790","name":"Tabea Grimm","image":{"@type":"ImageObject","inLanguage":"no-NO","@id":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d89e7879d34b46538837b714392142d83287fe766f1e9b783bea5ac9142e5d05?s=96&d=mm&r=g","caption":"Tabea Grimm"},"url":"https:\/\/hillsong.com\/germany\/no\/author\/tabea-grimm\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/posts\/633029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/users\/51263"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/comments?post=633029"}],"version-history":[{"count":2,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/posts\/633029\/revisions"}],"predecessor-version":[{"id":633045,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/posts\/633029\/revisions\/633045"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/media?parent=633029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/categories?post=633029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/no\/wp-json\/wp\/v2\/tags?post=633029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}