{"id":633260,"date":"2020-11-19T17:33:44","date_gmt":"2020-11-19T17:33:44","guid":{"rendered":"https:\/\/hillsong.com\/germany\/?p=633260"},"modified":"2020-11-24T18:02:04","modified_gmt":"2020-11-24T18:02:04","slug":"koeln1advent","status":"publish","type":"post","link":"https:\/\/hillsong.com\/germany\/pt\/event\/2020\/11\/koeln1advent\/","title":{"rendered":"1. ADVENT | MICRO CHURCH"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-pt\">Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em <a href=\"https:\/\/hillsong.com\/germany\/de\/wp-json\/wp\/v2\/posts\/633260\/\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p><p>WILLKOMMEN ZU MICRO CHURCH<\/p>\n<p>Feiern den 1. Advent mit uns.<br \/>\nEntdecke den wunderbaren Ratgeber.<\/p>\n<p>____<\/p>\n<p>Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst und geben Gott die Ehre.<br \/>\nMit MICRO CHURCH schaffen wir eine neue Art f\u00fcr dich, Teil unseren Online-Gottesdienst zu sein und gleichzeitig Gemeinschaft zu erleben.\u00a0\u00a0Wir treffen uns in Gruppen von ca. 30 \u2013 80 Leuten (je nach Geb\u00e4ude und lokalen COVID-19 Bestimmungen) und erleben den Online-Gottesdienst gemeinsam.<br \/>\nJeder ist willkommen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Deutsch.WILLKOMMEN ZU MICRO CHURCH Feiern den 1. Advent mit uns. Entdecke den wunderbaren Ratgeber. ____ Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst [&hellip;]<\/p>\n","protected":false},"author":51262,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14965,271,15367],"tags":[15339],"class_list":["post-633260","post","type-post","status-publish","format-standard","hentry","category-events-germany","category-germany","category-koln","tag-koln"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:de]1. ADVENT | MICRO CHURCH[:] - Dach\" \/>\n<meta property=\"og:description\" content=\"Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Deutsch.WILLKOMMEN ZU MICRO CHURCH Feiern den 1. Advent mit uns. Entdecke den wunderbaren Ratgeber. ____ Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dach\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T17:33:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-24T18:02:04+00:00\" \/>\n<meta name=\"author\" content=\"Jenny Alloway\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenny Alloway\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\"},\"author\":{\"name\":\"Jenny Alloway\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"headline\":\"1. ADVENT | MICRO CHURCH\",\"datePublished\":\"2020-11-19T17:33:44+00:00\",\"dateModified\":\"2020-11-24T18:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\"},\"wordCount\":102,\"commentCount\":0,\"keywords\":[\"K\u00f6ln\"],\"articleSection\":[\"Events\",\"Germany\",\"K\u00f6ln\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\",\"url\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\",\"name\":\"[:de]1. ADVENT | MICRO CHURCH[:] - Dach\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\"},\"datePublished\":\"2020-11-19T17:33:44+00:00\",\"dateModified\":\"2020-11-24T18:02:04+00:00\",\"author\":{\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\"},\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1. ADVENT | MICRO CHURCH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#website\",\"url\":\"https:\/\/hillsong.com\/germany\/fr\/\",\"name\":\"Dach\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b\",\"name\":\"Jenny Alloway\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g\",\"caption\":\"Jenny Alloway\"},\"url\":\"https:\/\/hillsong.com\/germany\/pt\/author\/jenny-alloway\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:de]1. ADVENT | MICRO CHURCH[:] - Dach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/","og_locale":"pt_PT","og_type":"article","og_title":"[:de]1. ADVENT | MICRO CHURCH[:] - Dach","og_description":"Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Deutsch.WILLKOMMEN ZU MICRO CHURCH Feiern den 1. Advent mit uns. Entdecke den wunderbaren Ratgeber. ____ Wie wir in den letzten Monaten erlebt haben, kann die Teilnahme an Gottesdiensten ganz unterschiedlich aussehen. Mit Zusammenk\u00fcnften an vielen verschiedenen Standorten und in Wohnzimmern feiern wir in kleineren Gruppen gemeinsam unseren Online-Gottesdienst [&hellip;]","og_url":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/","og_site_name":"Dach","article_published_time":"2020-11-19T17:33:44+00:00","article_modified_time":"2020-11-24T18:02:04+00:00","author":"Jenny Alloway","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jenny Alloway"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#article","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/"},"author":{"name":"Jenny Alloway","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"headline":"1. ADVENT | MICRO CHURCH","datePublished":"2020-11-19T17:33:44+00:00","dateModified":"2020-11-24T18:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/"},"wordCount":102,"commentCount":0,"keywords":["K\u00f6ln"],"articleSection":["Events","Germany","K\u00f6ln"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/","url":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/","name":"[:de]1. ADVENT | MICRO CHURCH[:] - Dach","isPartOf":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#website"},"datePublished":"2020-11-19T17:33:44+00:00","dateModified":"2020-11-24T18:02:04+00:00","author":{"@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b"},"breadcrumb":{"@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/germany\/it\/event\/2020\/11\/koeln1advent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/germany\/"},{"@type":"ListItem","position":2,"name":"1. ADVENT | MICRO CHURCH"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/germany\/fr\/#website","url":"https:\/\/hillsong.com\/germany\/fr\/","name":"Dach","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/germany\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/hillsong.com\/germany\/fr\/#\/schema\/person\/a4490e8541631c6cace3c23474637d9b","name":"Jenny Alloway","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cf5ab9ae06dc87f9a96b178ec4eed14e30bfdfd2ae7616c36ce6d61bdb83d52?s=96&d=mm&r=g","caption":"Jenny Alloway"},"url":"https:\/\/hillsong.com\/germany\/pt\/author\/jenny-alloway\/"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/posts\/633260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/users\/51262"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/comments?post=633260"}],"version-history":[{"count":3,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/posts\/633260\/revisions"}],"predecessor-version":[{"id":633399,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/posts\/633260\/revisions\/633399"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/media?parent=633260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/categories?post=633260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hillsong.com\/germany\/pt\/wp-json\/wp\/v2\/tags?post=633260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}