{"id":604793,"date":"2020-04-14T00:00:00","date_gmt":"2020-04-14T00:00:00","guid":{"rendered":"https:\/\/hillsong.com\/?page_id=604793"},"modified":"2025-10-17T21:04:04","modified_gmt":"2025-10-17T21:04:04","slug":"onlinegiving","status":"publish","type":"page","link":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/","title":{"rendered":"Online Giving"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":14609,"featured_media":0,"parent":422882,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-604793","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online Giving - USA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:en]Online Giving[:] - USA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/\" \/>\n<meta property=\"og:site_name\" content=\"USA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T21:04:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/\",\"url\":\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/\",\"name\":\"[:en]Online Giving[:] - USA\",\"isPartOf\":{\"@id\":\"https:\/\/hillsong.com\/usa\/#website\"},\"datePublished\":\"2020-04-14T00:00:00+00:00\",\"dateModified\":\"2025-10-17T21:04:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hillsong.com\/usa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"California\",\"item\":\"https:\/\/hillsong.com\/usa\/california\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Online Giving\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hillsong.com\/usa\/#website\",\"url\":\"https:\/\/hillsong.com\/usa\/\",\"name\":\"USA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hillsong.com\/usa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:en]Online Giving[:] - USA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/","og_locale":"en_US","og_type":"article","og_title":"[:en]Online Giving[:] - USA","og_url":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/","og_site_name":"USA","article_modified_time":"2025-10-17T21:04:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/","url":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/","name":"[:en]Online Giving[:] - USA","isPartOf":{"@id":"https:\/\/hillsong.com\/usa\/#website"},"datePublished":"2020-04-14T00:00:00+00:00","dateModified":"2025-10-17T21:04:04+00:00","breadcrumb":{"@id":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hillsong.com\/usa\/california\/onlinegiving\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hillsong.com\/usa\/california\/onlinegiving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hillsong.com\/usa\/"},{"@type":"ListItem","position":2,"name":"California","item":"https:\/\/hillsong.com\/usa\/california\/"},{"@type":"ListItem","position":3,"name":"Online Giving"}]},{"@type":"WebSite","@id":"https:\/\/hillsong.com\/usa\/#website","url":"https:\/\/hillsong.com\/usa\/","name":"USA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hillsong.com\/usa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/pages\/604793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/users\/14609"}],"replies":[{"embeddable":true,"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/comments?post=604793"}],"version-history":[{"count":4,"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/pages\/604793\/revisions"}],"predecessor-version":[{"id":642014,"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/pages\/604793\/revisions\/642014"}],"up":[{"embeddable":true,"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/pages\/422882"}],"wp:attachment":[{"href":"https:\/\/hillsong.com\/usa\/wp-json\/wp\/v2\/media?parent=604793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}